{"id":199793,"date":"2020-12-21T19:40:16","date_gmt":"2020-12-21T18:40:16","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=199793"},"modified":"2020-12-21T19:40:18","modified_gmt":"2020-12-21T18:40:18","slug":"comune-di-cagliari-eroga-buoni-spesa","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/12\/21\/comune-di-cagliari-eroga-buoni-spesa\/","title":{"rendered":"Comune di Cagliari eroga buoni spesa."},"content":{"rendered":"\n<p>Cagliari, 21 Dic 2020 - L'Amministrazione Comunale proceder\u00e0 all'erogazione dei buoni spesa previsti dal Decreto Legge del 23\/11\/2020 n. 154 (art. 2), e dall\u2019Ordinanza n. 658 del 29 marzo 2020 della Presidenza del Consiglio dei Ministri - Dipartimento della Protezione Civile, dal 22 dicembre 2020, secondo le modalit\u00e0 di seguito riportate.<br>A seguito dell'istruttoria delle domande presentate online tramite la piattaforma messa a disposizione nel sito istituzionale (scadenza presentazione domande 15\/12\/2020 ore 23:59), l'Amministrazione ha provveduto ad individuare i beneficiari e a quantificare l'importo da erogare ai singoli nuclei familiari.<br>Il buono spesa sar\u00e0 erogato tramite accreditamento della somma spettante sulla tessera sanitaria del richiedente che ha presentato domanda.<br>Sar\u00e0 possibile effettuare la spesa solo dopo aver ricevuto l'SMS di erogazione del credito sul numero di cellulare dichiarato nella domanda.<br>Si possono acquistare unicamente generi alimentari, di prima necessit\u00e0 e farmaci.<br>A fronte di ogni acquisto verr\u00e0 emesso uno scontrino con l'importo speso e l'importo residuo.<br>I buoni Spesa possono essere utilizzati presso gli esercizi commerciali indicati nell'elenco pubblicato nel sito istituzionale del Comune di Cagliari.<br>I buoni spesa dovranno essere utilizzati entro e non oltre il 28 febbraio 2021.<br>Per ogni ulteriore informazione si pu\u00f2 contattare il numero 070\/6774000 nei seguenti giorni e orari: dal luned\u00ec al gioved\u00ec dalle 9,00 alle 13,00 e dalle 15,00 alle 18,00 (esclusi i pomeriggi del 24 e 31 dicembre 2020).<br>Per gli esercizi commerciali: Tutti gli esercizi commerciali, presenti nel territorio cittadino, non ancora convenzionati con la DAY Ristoservice SPA, che fornisce il servizio di erogazione dei buoni spesa per conto del Comune, possono, se interessati, inviare una mail contenente il nome dell'insegna, la partita IVA e il telefono del referente dell'esercizio commerciale, al seguente indirizzo mail:<a href=\"javascript:webmail.View.mailto(%7bmailto:'buonispesa@day.it',%20subject:%20''%7d)\">\u00a0buonispesa@day.it\u00a0<\/a>e, per conoscenza, all'indirizzo<a href=\"javascript:webmail.View.mailto(%7bmailto:'servizi.sociali@comune.cagliari.it',%20subject:%20''%7d)\">\u00a0servizi.sociali@comune.cagliari.it<\/a><\/p>\n\n\n\n<p>Tutte le informazione e gli elenchi degli esercizi commerciali al link<a href=\"http:\/\/www.comune.cagliari.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;www.comune.cagliari.it&nbsp;<\/a>Con preghiera di cortese diffusione. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 21 Dic 2020 &#8211; L&#8217;Amministrazione Comunale proceder\u00e0 all&#8217;erogazione dei buoni spesa previsti dal Decreto Legge del 23\/11\/2020 n. 154 (art. 2), e dall\u2019Ordinanza n.&#8230;<\/p>\n","protected":false},"author":2,"featured_media":132550,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/199793"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=199793"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/199793\/revisions"}],"predecessor-version":[{"id":199794,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/199793\/revisions\/199794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/132550"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=199793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=199793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=199793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}