{"id":192399,"date":"2020-07-27T18:10:49","date_gmt":"2020-07-27T16:10:49","guid":{"rendered":"https:\/\/www.cronacaonline.it\/?p=192399"},"modified":"2020-07-27T18:11:53","modified_gmt":"2020-07-27T16:11:53","slug":"gdf-olbia-sequestrati-ad-olbia-isola-bianca-6-chilogrammi-di-cocaina-i-controlli-delle-unita-cinofile-interrompono-ancora-il-grande-flusso-di-droghe-pesanti-verso-lisola-e-arrestano-un-35e","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/07\/27\/gdf-olbia-sequestrati-ad-olbia-isola-bianca-6-chilogrammi-di-cocaina-i-controlli-delle-unita-cinofile-interrompono-ancora-il-grande-flusso-di-droghe-pesanti-verso-lisola-e-arrestano-un-35e\/","title":{"rendered":"Gdf Olbia &#8211; Sequestrati ad Olbia Isola Bianca 6 chilogrammi di Cocaina: i controlli delle unit\u00e0 cinofile interrompono ancora il grande flusso di droghe pesanti verso l\u2019isola e arrestano un 35enne italiano."},"content":{"rendered":"\n<p>Olbia, 27 Lug 2020 - I militari della Guardia di Finanza del Gruppo di Olbia con unit\u00e0 cinofili hanno arrestato un 35enne italiano residente in provincia di Nuoro, mentre tentava di introdurre in Sardegna, utilizzando la propria autovettura, un\u2019ingente quantit\u00e0 di cocaina.<\/p>\n\n\n\n<p>In particolare, nel corso di specifici controlli posti in essere allo sbarco della motonave proveniente da Livorno, presso il porto Isola Bianca di Olbia, l\u2019attenzione dei finanzieri \u00e8 stata richiamata da un soggetto che alla guida di un veicolo tentava inutilmente di defilarsi per evitare il controllo.<\/p>\n\n\n\n<p>L\u2019evidente segnalazione dei pastori tedeschi addestrati alla ricerca di sostanze stupefacenti, Daff e Semia, e con le risposte contraddittorie fornite dal presunto trafficante, in evidente stato di nervosismo, alle preliminari domande dei militari, hanno poi convinto questi ultimi ad approfondire il controllo sul mezzo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2020\/07\/Finanzieri-gruppo-Olbia-con-cani-antidroga.jpg\" alt=\"\" class=\"wp-image-192401\" width=\"725\" height=\"451\" srcset=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2020\/07\/Finanzieri-gruppo-Olbia-con-cani-antidroga.jpg 600w, https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2020\/07\/Finanzieri-gruppo-Olbia-con-cani-antidroga-300x187.jpg 300w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/><\/figure>\n\n\n\n<p>L\u2019autovettura, sottoposta ad una minuziosa perquisizione ha rivelato un doppiofondo artigianale, abilmente ricavato all\u2019interno del cruscotto ed accessibile attraverso un\u2019apertura sotto il copri ruota, contenente il prezioso carico illegale: 6 pacchi di cocaina di altissima qualit\u00e0 per un totale complessivo di 6 chilogrammi, ben sigillati e posti sottovuoto con l\u2019evidente intenzione di nascondere il pungente odore della droga e confondere il fiuto dei cani.<\/p>\n\n\n\n<p>Visto l\u2019importante quantitativo e l\u2019elevata qualit\u00e0 della droga che ne avrebbe consentito diversi \u201ctagli\u201d senza comprometterne gli effetti stupefacenti, i finanzieri hanno maturato l\u2019idea di non trovarsi di fronte ad un trafficante \u201cdell\u2019ultima ora\u201d ma di un soggetto ben inserito negli ambienti della malavita e che farebbe del traffico di stupefacenti la propria attivit\u00e0 principale.<\/p>\n\n\n\n<p>La sostanza sequestrata, una volta tagliata ed immessa sul mercato, avrebbe potuto fruttare oltre un milione di euro.<\/p>\n\n\n\n<p>Al termine delle attivit\u00e0, il soggetto \u00e8 stato arrestato per traffico di sostanze stupefacenti e posto a disposizione dell\u2019Autorit\u00e0 Giudiziaria di Tempio Pausania che ne ha disposto l\u2019immediata traduzione presso il carcere di Bancali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olbia, 27 Lug 2020 &#8211; I militari della Guardia di Finanza del Gruppo di Olbia con unit\u00e0 cinofili hanno arrestato un 35enne italiano residente in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":192400,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/192399"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=192399"}],"version-history":[{"count":1,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/192399\/revisions"}],"predecessor-version":[{"id":192402,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/192399\/revisions\/192402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/192400"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=192399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=192399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=192399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}