{"id":191211,"date":"2020-04-02T08:56:33","date_gmt":"2020-04-02T06:56:33","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=186987"},"modified":"2020-04-02T08:56:33","modified_gmt":"2020-04-02T06:56:33","slug":"coronavirus-ursula-von-der-leyen-si-scusa-con-litalia-siamo-con-voi","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/02\/coronavirus-ursula-von-der-leyen-si-scusa-con-litalia-siamo-con-voi\/","title":{"rendered":"Coronavirus &#8211; Ursula Von Der Leyen si scusa con l\u2019Italia: siamo con voi"},"content":{"rendered":"<p>Bruxelles, 2 Apr 2020 - Passo indietro della presidente della Commissione ue Ursula von der Leyen che, in una lettera aperta a la Repubblica, scrive che \"il Paese colpito pi\u00f9' duramente, l'Italia, \u00e8 diventato anche la pi\u00f9 grande fonte di ispirazione per noi tutti\" e che \"solo la solidariet\u00e0 pu\u00f2 farci riemergere da questa crisi - quella tra persone come quella tra Stati\". E von del Leyen di fatto si scusa con il nostro Paese, dicendo che \"oggi l'Europa si sta mobilitando al fianco dell'Italia\" anche se \"purtroppo non \u00e8 stato sempre cos\u00ec\" perci\u00f2 \"bisogna riconoscere che nei primi giorni della crisi, di fronte al bisogno di una risposta comune europea, in troppi hanno pensato solo ai problemi di casa propria\" mentre \"non si rendevano conto che possiamo sconfiggere questa pandemia solo insieme, come Unione\".<\/p>\n<p>\u00c8 stato un comportamento dannoso - ammette Von der Leyen - e che poteva essere evitato\", tanto pi\u00f9 che\u00a0\"in questi giorni la distanza tra individui \u00e8 fondamentale per la nostra sicurezza: la distanza tra nazioni europee, al contrario, mette tutti in pericolo\".<\/p>\n<p>La presidente della Commissione Ue garantisce che \"l'Europa ha cambiato passo\", tanto da voler \"dare una mano, stanziando nuove risorse per finanziare la cassa integrazione\", cos\u00ec l'Unione stanzier\u00e0 \"fino a cento miliardi di euro in favore dei Paesi colpiti pi\u00f9 duramente, a partire dall'Italia, per compensare la riduzione degli stipendi di chi lavora con un orario ridotto. Questo sar\u00e0 possibile grazie a prestiti garantiti da tutti gli Stati membri - dimostrando cos\u00ec vera solidariet\u00e0 europea\" garantisce Von der Leyen, che conclude cos\u00ec il suo intervento sul quotidiano italiano: \"Questa crisi \u00e8 una prova per l'Europa. E non possiamo permetterci di fallire. Le decisioni che prendiamo oggi verranno ricordate per anni. Daranno forma all'Europa di domani. Credo che l'Europa possa riemergere pi\u00f9 forte da questa situazione, ma dobbiamo prendere le decisioni giuste - qui ed ora\". Perch\u00e9 quel che ha in mente Von der Leyen \u00e8 \"un'Europa fondata sulla solidariet\u00e0 - la nostra pi\u00f9 grande speranza e il nostro investimento in un futuro comune\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruxelles, 2 Apr 2020 &#8211; Passo indietro della presidente della Commissione ue Ursula von der Leyen che, in una lettera aperta a la Repubblica, scrive&#8230;<\/p>\n","protected":false},"author":2,"featured_media":186988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/191211"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=191211"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/191211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/186988"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=191211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=191211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=191211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}