{"id":189768,"date":"2020-06-02T12:18:49","date_gmt":"2020-06-02T10:18:49","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=189768"},"modified":"2020-06-02T12:18:49","modified_gmt":"2020-06-02T10:18:49","slug":"dipendente-di-un-market-di-olbia-sottrae-merce-varie-deferito-in-stato-di-liberta-dai-carabinieri-del-reparto-territoriale-della-citta","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/06\/02\/dipendente-di-un-market-di-olbia-sottrae-merce-varie-deferito-in-stato-di-liberta-dai-carabinieri-del-reparto-territoriale-della-citta\/","title":{"rendered":"Dipendente di un market di Olbia sottrae merce varie: deferito in stato di libert\u00e0 dai carabinieri del Reparto Territoriale della citt\u00e0"},"content":{"rendered":"<p>Olbia, 2 Giu 2020 - I Carabinieri della Stazione di Olbia Centro, coordinati dal comando del Reparto Territoriale di Olbia, hanno deferito in stato di libert\u00e0 un 52enne, dipendente di un supermercato del gruppo \u201cNonna Isa\u201d di Olbia, per furto aggravato e continuato.<\/p>\n<p>\u00c8 stato uno dei militari dell\u2019Arma, libero dal servizio, a notare l\u2019uomo in atteggiamenti non del tutto chiari. Pertanto gli investigatori dell\u2019Arma hanno poi deciso d\u2019approfondire la questione e avviare una mirata attivit\u00e0 di osservazione che, a seguito di ripetuti appostamenti, ha consentito di accertare che l\u2019uomo, in modo sistematico, utilizzando l\u2019uscita secondaria, movimentava scatole e buste dal punto vendita verso la sua auto.<\/p>\n<p>Quindi i militari hanno documentato che l\u2019uomo si impossessava dei prodotti arrivando con largo anticipo a lavoro, gi\u00e0 dalle primissime ore del mattino, in modo da aver tutto il tempo necessario per selezionarli e nasconderli, trasferendoli all\u2019esterno su dei carrelli e simulando di dover buttare dei rifiuti, per poi nasconderli nella vettura quando si trovava fuori del raggio d\u2019azione delle telecamere di sicurezza del supermercato.<\/p>\n<p>Quindi gli investigatori dell\u2019Arma dopo aver raccolto tutti gli elementi necessari, sono intervenuti fermando l\u2019uomo mentre si allontanava al termine di un turno di lavoro. Subito dopo, durante il controllo dell\u2019auto, all\u2019interno sono state trovate le buste e alcune scatole contenenti merce di vario genere (alimentari e no-food) per un valore superiore ai 200 euro, chiaramente parte dell\u2019assortimento del negozio.<\/p>\n<p>Poi gli stessi tipi di prodotti sono stati rinvenuti anche presso l\u2019abitazione, sottoposta successivamente a perquisizione.<\/p>\n<p>Per l\u2019uomo, oltre ad aver causato forti danni economici ed aver collezionato una denuncia in stato libert\u00e0 all\u2019A.G. competente presso la Procura della Repubblica di Tempio Pausania, che ha coordinato le indagini, \u00e8 venuto meno il rapporto di fiducia con l\u2019azienda che ne ha disposto l\u2019immediato licenziamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olbia, 2 Giu 2020 &#8211; I Carabinieri della Stazione di Olbia Centro, coordinati dal comando del Reparto Territoriale di Olbia, hanno deferito in stato di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":189769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/189768"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=189768"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/189768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/189769"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=189768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=189768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=189768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}