{"id":187670,"date":"2020-04-15T07:45:27","date_gmt":"2020-04-15T05:45:27","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187670"},"modified":"2020-04-15T07:45:27","modified_gmt":"2020-04-15T05:45:27","slug":"mes-pd-iv-ed-anche-berlusconi-premono-su-conte-per-dire-si-ai-fondi-europei-sono-senza-condizioni","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/15\/mes-pd-iv-ed-anche-berlusconi-premono-su-conte-per-dire-si-ai-fondi-europei-sono-senza-condizioni\/","title":{"rendered":"Mes. Pd-Iv ed anche Berlusconi premono su Conte per dire s\u00ec ai fondi europei, sono senza condizioni"},"content":{"rendered":"<p>Roma, 15 Apr 2020 - Cresce la pressione del PD sul presidente del consiglio perch\u00e9 l'Italia accetti i 36 miliardi di euro del Mes: \"Sul tavolo c'\u00e8 una linea di credito fino al 2% del Pil per le spese sanitarie - ragionano - sono circa 36 miliardi, ci rifai gli ospedali italiani, metti su il Covid Hospital con quei soldi, non c'entra niente la Troika\". Nicola Zingaretti lo dice chiaro: \"Da governatore pi\u00f9 che da segretario Pd dico: se esister\u00e0 l'uso senza condizionalit\u00e0 di avere dei miliardi per la nostra sanit\u00e0 io credo che dovremo prenderle queste risorse\". Matteo Renzi, dal canto suo, non ha mai avuto dubbi: \"Il Mes senza condizionalit\u00e0 va usato di corsa, piaccia o non piaccia ai populisti di maggioranza e opposizione. E vedrete che l'Italia user\u00e0 tutto: Bce, Mes, Sure, Recovery Fund. Tutto\", scandisce. Ed \u00e8 stato soltanto ieri che Romano Prodi aveva espresso esattamente lo stesso concetto.<\/p>\n<p>Ribadisce il suo sonoro no, invece, il M5S. Nel mezzo, ancora una volta, il presidente del Consiglio. Luigi Di Maio ha buon gioco nel rievocare le parole pronunciate del premier all'indomani dell'Eurogruppo. \"L'Italia lo ritiene uno strumento totalmente inadeguato, non ha sottoscritto alcun prestito, di cui comunque non ne ha bisogno\", cos\u00ec aveva parlato Giuseppe Conte proprio per tranquillizzare il Movimento 5 Stelle sull'inclusione del Mes nel pacchetto di interventi europei per fronteggiare la crisi Coronavirus. \"Forse \u00e8 arrivato il momento di un mea culpa europeo, l'austerity ha fatto tagli sulla spesa pubblica e questo ha indebolito la sanit\u00e0 pubblica\", sostiene Di Maio. L'ex capo politico del Movimento non ha fatto accenno al fatto che i fondi anti-Coronavirus del Mes non sono soggetti a condizionalit\u00e0. Il no era e resta il no, almeno per ora.<\/p>\n<p>Sulla questione Mes la posizione di Forza Italia si avvicina molto a quella di Renzi e del Pd. \"Non dobbiamo assolutamente dire di no al Mes - dice Silvio Berlusconi - sarebbe un errore clamoroso rinunciare ad utilizzare i 36-37 miliardi che potremmo ottenere, senza condizioni, per sistemare il nostro sistema sanitario nazionale. Peraltro a un tasso di interesse inferiore a quelli di mercato\".<\/p>\n<p>Matteo Salvini e Giorgia Meloni, invece, insistono con il loro no al \"furto\" dell'Ue. Matteo Salvini chiede che il governo e il premier si presentino in Aula, non avendo \"mai\" ottenuto un mandato del Parlamento. Per il leader leghista usare il Mes sarebbe \"come andare dallo strozzino\". Sulla stessa linea Giorgia Meloni: \"Aspettiamo che Conte venga in Parlamento. I fatti dicono che il ministro Gualtieri ha dato il via libera a un documento nel quale c'\u00e8 il Mes come possibilit\u00e0 per affrontare la crisi, mentre non ci sono gli Eurobond. Chiediamo al presidente del Consiglio di disconoscere questo documento al Consiglio europeo\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 15 Apr 2020 &#8211; Cresce la pressione del PD sul presidente del consiglio perch\u00e9 l&#8217;Italia accetti i 36 miliardi di euro del Mes: &#8220;Sul&#8230;<\/p>\n","protected":false},"author":2,"featured_media":187672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187670"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187670"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/187672"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}