{"id":187617,"date":"2020-04-14T08:10:03","date_gmt":"2020-04-14T06:10:03","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187617"},"modified":"2020-04-14T08:10:03","modified_gmt":"2020-04-14T06:10:03","slug":"cura-italia-liquidate-oltre-1-milione-indennita-600-euro-45-milioni-le-domande","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/14\/cura-italia-liquidate-oltre-1-milione-indennita-600-euro-45-milioni-le-domande\/","title":{"rendered":"Cura-Italia, liquidate oltre 1 milione indennit\u00e0 600 euro: 4,5 milioni le domande"},"content":{"rendered":"<p>Roma, 14 Apr 2020 - Sono state presentate oltre 4,5 milioni di domande per\u00a0le prestazioni previste dal decreto Cura Italia, relative a oltre 8,8 milioni di\u00a0beneficiari: quasi 4 milioni di istanze hanno riguardato l'indennit\u00e0 da 600\u00a0euro e l'Inps ne ha gi\u00e0\u00a0liquidate oltre 1 milione e continuer\u00e0 fino a\u00a0marted\u00ec. E' quanto fa sapere Palazzo Chigi. Le indennit\u00e0 - si precisa -\u00a0verranno pagate nei conti correnti dei beneficiari con valuta dal 15 aprile al\u00a017, anche grazie alla collaborazione del mondo bancario, che permette\u00a0l'accredito diretto in un solo giorno lavorativo.<\/p>\n<p>Gli uffici di Inps e banche - si\u00a0sostiene - sono rimasti aperti anche durante il weekend di\u00a0Pasqua per velocizzare l'iter di attuazione delle misure di\u00a0sostegno ai lavoratori e alle famiglie previsti dal governo per\u00a0far fronte all'emergenza Covid-19. Operativi nei giorni festivi\u00a0anche gli uffici della Ragioneria Generale dello Stato per\u00a0assicurare l'attuazione dei pagamenti, si aggiunge.<\/p>\n<p>\"I 200.000 congedi parentali richiesti sono stati retribuiti per la grande maggioranza direttamente dalle aziende ai dipendenti, mentre le oltre 40mila domande per il bonus baby sitting sono al vaglio dell'Inps per andare in pagamento (nel libretto di famiglia) il 15 aprile anch'esse\" si legge ancora nella nota del governo.<\/p>\n<p>L'Inps sta raccogliendo le domande\u00a0che iniziano ad arrivare dalle Regioni per quanto riguarda la\u00a0cassa integrazione in deroga. Lo si legge nella nota in cui si precisa che al momento sono 11 le Regioni che\u00a0stanno provvedendo all'invio dei dati. \u00c8 gi\u00e0 in corso il\u00a0pagamento da parte dell'Inps della cassa in deroga delle prime Regioni.<\/p>\n<p>\u201c\u00c8 in piena operativit\u00e0 la\u00a0convenzione siglata da Abi, Inps e organizzazioni sindacali che\u00a0consente ai lavoratori sospesi dal lavoro a causa dell'emergenza\u00a0Covid-19 di ricevere un anticipo della cassa integrazione\u00a0ordinaria e in deroga, pari a 1.400 euro\", si legge ancora. \"Per ottenere le erogazioni, le procedure non richiedono pi\u00f9\u00a0l'invio di modelli cartacei validati presso sportelli bancari e\u00a0postali per certificare l'Iban, perch\u00e9 la validit\u00e0 del codice\u00a0identificativo viene effettuata con sistemi informatici. Nei\u00a0giorni scorsi, l'Abi ha comunicato che la quasi totalit\u00e0 delle\u00a0banche italiane (quasi il 94% in termini di attivi) ha gi\u00e0\u00a0aderito alla Convenzione. \u00c8 bene ricordare che i tempi ordinari\u00a0per il pagamento della cassa integrazione sono sempre stati di\u00a0due o tre mesi. In questo caso, grazie alla normativa\u00a0semplificata e allo sforzo enorme dell'Inps, i pagamenti arriveranno al pi\u00f9 tardi entro 30 giorni dalla ricezione della\u00a0domanda\", precisa la stessa nota.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 14 Apr 2020 &#8211; Sono state presentate oltre 4,5 milioni di domande per\u00a0le prestazioni previste dal decreto Cura Italia, relative a oltre 8,8 milioni&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187617"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187617"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/2027"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}