{"id":187615,"date":"2020-04-14T08:05:56","date_gmt":"2020-04-14T06:05:56","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187615"},"modified":"2020-04-14T08:05:56","modified_gmt":"2020-04-14T06:05:56","slug":"coronavirus-ministro-boccia-chi-vuole-riaprire-se-ne-assume-la-responsabilita","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/14\/coronavirus-ministro-boccia-chi-vuole-riaprire-se-ne-assume-la-responsabilita\/","title":{"rendered":"Coronavirus, ministro Boccia: &#8220;Chi vuole riaprire se ne assume la responsabilit\u00e0&#8221;"},"content":{"rendered":"<p>Roma, 14 Apr 2020 - \"Capisco la voglia di uscirne, ma i numeri ci dicono che siamo ancora dentro l'emergenza\" pertanto \"i presidenti che vogliono riaprire se ne assumono la responsabilit\u00e0\". Cos\u00ec il ministro per gli Affari regionali Francesco Boccia, che in un'intervista al Corriere della Sera dice che \"parlare di normalit\u00e0 vuol dire illudere la gente\" e se si commette un errore \"distruggi settimane di sacrifici di tutti\". E a chi non ha colto l'insegnamento di questi 45 giorni, il ministro ricorda che \"l'Italia conta 160 mila casi e 20 mila morti\".<\/p>\n<p>Boccia prosegue spiegando che \"nella fase due entreremo dal 4 maggio, dobbiamo ancora mantenere la barra dritta\" mentre ora ci troviamo ancora \"nella fase in cui vediamo le prime luci e dobbiamo difendere i risultati raggiunti\" e pur comprendendo desideri e necessita, il ministro propone un paragone con la Francia: \"Se il presidente Emmanuel Macron prolunga il confinamento all'11 maggio, \u00e8 perch\u00e9 sa che senza salute non c'\u00e8 economia\" afferma Boccia.<\/p>\n<p>E se da un lato ai fautori \"dell'aprire a tutti i costi\" il ministro ricorda che \"la solidariet\u00e0 \u00e8 venuta dal volontariato, dai medici e dagli infermieri partiti anche a Pasqua per andare in corsia al Nord, mettendo a rischio la loro salute\", dall'altro riserva anche una riflessione sul sistema in generale dicendo: \"Mettere ordine con 21 sistemi regionali diversi \u00e8 un obiettivo ambizioso. Quello che puoi ottenere, \u00e8 che la nave Italia segua la stessa rotta\". Cos\u00ec Boccia ripete: \"I presidenti che vogliono riaprire se ne assumono la responsabilit\u00e0, come ho detto a Fugatti che guida la Provincia di Trento e vuole sbloccare alcuni cantieri. Non \u00e8 meglio aspettare la valutazione sulle classi di rischio di ciascun lavoratore, pronta fra sei o sette giorni? Perch\u00e9 partire prima, rischiando che si accenda un focolaio?\" si chiede il ministro che per altro consiglia \"di seguire le linee della comunit\u00e0 scientifica e le scelte del governo\u201d.<\/p>\n<p>Poi conclude: \"Zaia avr\u00e0 fatto le sue valutazioni sulla base dei contagi, ma io penso che se qualche presidente di Regione apre i cantieri senza aspettare le classificazioni di rischio dell'Inail si assume la responsabilit\u00e0 delle forzature\", insiste Boccia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 14 Apr 2020 &#8211; &#8220;Capisco la voglia di uscirne, ma i numeri ci dicono che siamo ancora dentro l&#8217;emergenza&#8221; pertanto &#8220;i presidenti che vogliono&#8230;<\/p>\n","protected":false},"author":2,"featured_media":186765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187615"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187615"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/186765"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}