{"id":187419,"date":"2020-04-09T17:24:53","date_gmt":"2020-04-09T15:24:53","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187419"},"modified":"2020-04-09T17:24:53","modified_gmt":"2020-04-09T15:24:53","slug":"eurogruppo-nuova-riunione-premier-olandese-rutte-possibile-accordo-ma-dibattito-complicato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/09\/eurogruppo-nuova-riunione-premier-olandese-rutte-possibile-accordo-ma-dibattito-complicato\/","title":{"rendered":"Eurogruppo, nuova riunione. Premier olandese Rutte: possibile accordo, ma dibattito complicato"},"content":{"rendered":"<p>Bruxelles, 9 Apr 2020 - L'inizio dell'Eurogruppo previsto in videoconferenza per le 17 slitta di un'ora, alle 18. Lo comunica un portavoce, spiegando che sono in corso contatti bilaterali per favorire la discussione.<\/p>\n<p>La riunione di oggi \u00e8 la continuazione di quella del 7 aprile. Tema centrale della discussione le sfide di economia politica legate al Coronavirus.\u00a0Sono in corso discussioni serrate per preparare la riunione dei ministri finanziari per cercare un compromesso sugli strumenti finanziari per rilanciare la crescita.<\/p>\n<p>Solidali, ma contrari all'emissione di debito comune. \"Sulle condizioni per il Mes non dir\u00f2 niente\". Cos\u00ec il premier olandese Mark Rutte, in una conferenza stampa. Rutte ha difeso la posizione negoziale del ministro delle finanze Woepke Hoekstra all'Eurogruppo, ribadendo che i Paesi Bassi non sono soli nel dibattito, specialmente sugli Eurobond. Secondo il premier alla riunione \u00e8 possibile un accordo, ma il dibattito \u00e8 complicato.<\/p>\n<p>\u200bContinuano le trattative. Il Parlamento olandese in precedenza aveva approvato due risoluzioni che esortavano il governo a non accettare gli Eurobond e a tenere il punto sulla condizionalit\u00e0 per l'utilizzo del Mes.\u00a0Le mozioni, presentate rispettivamente dal partito anti-Ue Forum per la democrazia (FvD) e da una formazione trasversale di deputati, non sono vincolanti, ma danno un chiaro indirizzo politico al governo impegnato nei negoziati all'Eurogruppo.<\/p>\n<p>\"La Francia e la Germania lavorano a un compromesso\" in vista della riunione dell'Eurogruppo di questo pomeriggio che deve tentare di trovare un accordo sul pacchetto per rispondere all'impatto economico della crisi del Coronavirus. Lo hanno detto fonti del ministero delle Finanze francese. Le stesse fonti aggiungono che il Bruno Le Maire \u00e8 impegnato in una serie di discussioni telefoniche con alcuni suoi omologhi europei.<\/p>\n<p>\"Io ho parlato con Giuseppe Conte e\u00a0siamo d'accordo sul fatto che serve con urgenza solidariet\u00e0 in Europa in una delle ore pi\u00f9 difficili, se non la pi\u00f9 difficile. E\u00a0la Germania \u00e8 pronta per la solidariet\u00e0\", ha detto Angela Merkel a Berlino in conferenza stampa.<\/p>\n<p>Tuttavia, sui titoli di debito comune che dovrebbero servire per la risposta alla crisi provocata dal coronavirus, \"non c'\u00e8 consenso politico\". E' quanto ha ribadito in precedenza la cancelliera tedesca Angela Merkel nel corso di una conference call con i membri del suo partito, secondo quanto rivelato all'agenzia di stampa tedesca Dpa da uno dei partecipanti.<\/p>\n<p>\"Ci sono molti miliardi di euro\" a disposizione con gli strumenti che vengono discussi oggi all'Eurogruppo, ha detto la cancelliera Angela Merkel, aggiungendo di pensare in particolare a \"tre punti molto importanti\" come \"il programma nell'ambito del Mes e dell'allargamento delle attivit\u00e0 della Bei e il fondo europeo di contributo per il lavoro a orario ridotto\". A detta della cancelliera si tratta di \"mezzi molto efficaci\" che portano \"solidariet\u00e0 nella crisi\".<\/p>\n<p>Merkel ribadisce che \"la Germania dar\u00e0 il suo contributo alla solidariet\u00e0 europea, questo \u00e8 certo\". Dopodich\u00e9, dato che \"stiamo parlando di un impatto molto grave sulle nostre economie, \u00e8 necessario un programma di recupero e fondi di strutture volte ad avvicinare i Paesi\" colpiti dalla pandemia.<\/p>\n<p>L'atteggiamento dell'Olanda, che sta bloccando una risposta comune europea all'emergenza coronavirus con il suo 'no' ai coronabond e la sua insistenza per condizioni stringenti in caso di ricorso al Mes, \"\u00e8 irresponsabile\". La dura presa diposizione \u00e8 arrivata dall'ex presidente della Commissione europea,\u00a0Jean Claude Juncker, in un''intervista al quotidiano francese\u00a0Liberation.<\/p>\n<p>\"Se l'Europa non si dar\u00e0 strumenti finanziari all'altezza della sfida, come gli Eurobond, l'Italia sar\u00e0 costretta a far fronte all'emergenza e alla ripartenza con le proprie risorse. Ma le risposte nazionali rischiano di essere meno efficaci rispetto ad un'azione coordinata europea e possono mettere a repentaglio il sogno europeo\". Questo \u00e8 il ragionamento del premier Giuseppe Conte in una intervista alla Bild.<\/p>\n<p>\"In Germania potete avere tutto lo spazio fiscale che volete ma non potrete mai pensare di affrontare un'emergenza sanitaria, economica, sociale di cos\u00ec devastante impatto con il vostro spazio fiscale'', ha detto Conte alla Bild. ''\u00c8 nell'interesse reciproco che l'Europa batta un colpo, che sia all'altezza della sfida, altrimenti dobbiamo assolutamente abbandonare il sogno europeo e dire ognuno fa per s\u00e8 ma impiegheremo il triplo, il quadruplo, il quintuplo delle risorse per uscire da questa crisi e non avremo garanzia che ce la faremo nel modo migliore, pi\u00f9 efficace e tempestivo''. Restano dunque allineate le posizioni di Francia e Germania che spingono per trovare l'intesa. Perch\u00e9 un fallimento \"\u00e8 impensabile\".<\/p>\n<p>Una cancellazione dei debiti contratti per contrastare lo shock economico senza precedenti causato dal coronavirus? \"Mi sembra completamente impensabile, non \u00e8 il momento di farsi domande sulla cancellazione, in questo momento siamo concentrati su come sostenere l'economia\", ha detto la presidente della Bce Christine Lagarde alla radio francese\u00a0France inter. \"Pi\u00f9 in l\u00e0 vedremo come rimborsare i debiti e gestione le finanze pubbliche nel modo pi\u00f9 efficiente\".<\/p>\n<p>In precedenza la presidente della Bce Christine Lagarde aveva rinnovato il suo invito per una risposta di bilancio forte al coronavirus, chiedendo ai governi di superare le differenze. In un editoriale pubblicato su diversi quotidiani europei, e riportato dall'agenzia Bloomberg, Lagarde afferma: \"se non saranno curati tutti i paesi, gli altri soffriranno. La solidariet\u00e0 \u00e8 un interesse personale\". \u201c\u00c8 vitale che la risposta di bilancio alla crisi sia presa con sufficiente forza in tutte le parti dell'area euro\". Le politiche di bilancio e monetarie devono essere allineate, dice Christine Lagarde.<\/p>\n<p>\"Segnali preoccupanti\" iniziano ad apparire sul mercato del lavoro dell'area euro\", afferma ancora in un intervento su vari quotidiani europei fra i quali Le Monde. \"Se la disoccupazione ci mette di solito pi\u00f9 tempo ad aumentare in Europa ed \u00e8 meno volatile, dei primi segnali preoccupanti emergono\" osserva Lagarde, notando come negli Stati Uniti le richieste di sussidi sono schizzate nelle ultime due settimane.<\/p>\n<p>L'attivit\u00e0 economica in Italia e Spagna \u00e8 ferma, \"Noi dobbiamo garantire che tutti possano andare sui mercati allo stesso modo per affrontare la crisi\", dice in un'intervista a la Repubblica Josep Borrell, alto rappresentante dell'Ue per gli affari esteri e la politica di sicurezza. A poche ore dal fallimento dell'Eurogruppo, e alla vigilia della nuova riunione dei ministri delle finanze, l'esponente politico dei socialisti spagnoli commenta: \"E' chiaro che il supporto che Cina e Russia prestano ad altri paesi serve anche ad aumentare la loro influenza a livello globale\".<\/p>\n<p>Sin dalla crisi greca, l'alto funzionario Ue, favorevole agli Eurobond, sostiene la necessit\u00e0 di introdurre una capacit\u00e0 fiscale europea da affiancare alla Bce, \"per stabilizzare le economie e affrontare situazioni di crisi, come quella attuale in Italia. \u00c8 il momento di agire visto che i paesi pi\u00f9 colpiti dalla pandemia vanno incontro a una massiccio aumento del debito\".<\/p>\n<p>La Bce e la commissione \"hanno fatto la loro parte, ma potrebbe non bastare. Ora tocca ai governi. La proposta francese di un fondo per la ripresa economica \u00e8 una buona idea\".<\/p>\n<p>Borrell condivide l'idea della presidente Ursula von der Leyen di un piano Marshall europeo: \"Dobbiamo essere noi europei il nostro Marshall. E il piano va lanciato subito per preservare i nostri sistemi economici e la coesione sociale\".<\/p>\n<p>Bisogna ricordare \"che Francia e Germania hanno mandato pi\u00f9 mascherine al vostro paese rispetto alla Cina. E questa settimana un'equipe di medici europei finanziata dalla Ue sta lavorando fianco a fianco ai colleghi italiani in Lombardia. L'Europa c'\u00e8\".<\/p>\n<p>Per Borrell l'Ue \"deve dimostrarsi forte e coesa anche nell'aiutare Africa e sud America che \"saranno colpiti duramente dal virus, finche' non ne escono nemmeno noi saremo al sicuro\". La commissione \"ha reso disponibili 10,4 miliardi e la bei 5,2\" ma serve un coordinamento internazionale, per esempio a livello di G20, dobbiamo anche chiedere che le sanzioni non impediscono a paesi come Iran, Yemen, Siria e Venezuela di accedere agli aiuti umanitari internazionali\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruxelles, 9 Apr 2020 &#8211; L&#8217;inizio dell&#8217;Eurogruppo previsto in videoconferenza per le 17 slitta di un&#8217;ora, alle 18. Lo comunica un portavoce, spiegando che sono&#8230;<\/p>\n","protected":false},"author":2,"featured_media":187420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187419"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187419"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/187420"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}