{"id":187401,"date":"2020-04-09T08:46:36","date_gmt":"2020-04-09T06:46:36","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187401"},"modified":"2020-04-09T08:46:36","modified_gmt":"2020-04-09T06:46:36","slug":"lagarde-serve-risposta-bilancio-forte-curare-tutti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/09\/lagarde-serve-risposta-bilancio-forte-curare-tutti\/","title":{"rendered":"Lagarde: &#8220;Serve risposta bilancio forte, curare tutti&#8221;"},"content":{"rendered":"<p>Francoforte, 9 Apr 2020 - Christine Lagarde rinnova il suo invito per una risposta di bilancio forte al coronavirus, chiedendo ai governi di superare le differenze.<\/p>\n<p>In un editoriale pubblicato su diversi quotidiani europei, e riportato dall'agenzia Bloomberg, il presidente Bce afferma: \"Se non saranno curati tutti i Paesi, gli altri soffriranno. La solidariet\u00e0 \u00e8 un interesse personale\". \u201c\u00c8 vitale che la risposta di bilancio alla crisi sia presa con sufficiente forza in tutte le parti dell'area euro\".<\/p>\n<p>\"Segnali preoccupanti\" iniziano ad apparire sul mercato del lavoro dell'area euro, dice poi Lagarde. \"Se la disoccupazione ci mette di solito pi\u00f9 tempo ad aumentare in Europa ed \u00e8 meno volatile, dei primi segnali preoccupanti emergono\" osserva Lagarde, notando come negli Stati Uniti le richieste di sussidi siano schizzate nelle ultime due settimane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francoforte, 9 Apr 2020 &#8211; Christine Lagarde rinnova il suo invito per una risposta di bilancio forte al coronavirus, chiedendo ai governi di superare le&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187401"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187401"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/2016"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}