{"id":187233,"date":"2020-04-06T18:43:24","date_gmt":"2020-04-06T16:43:24","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187233"},"modified":"2020-04-06T18:43:24","modified_gmt":"2020-04-06T16:43:24","slug":"sagama-tentato-omicidio-di-un-allevatore-di-48-anni-del-paese-fermati-due-aggressori-e-i-carabinieri-cercano-gli-altri-due","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/06\/sagama-tentato-omicidio-di-un-allevatore-di-48-anni-del-paese-fermati-due-aggressori-e-i-carabinieri-cercano-gli-altri-due\/","title":{"rendered":"Sagama tentato omicidio di un allevatore di 48 anni del paese, fermati due aggressori e i carabinieri cercano gli altri due."},"content":{"rendered":"<p>Suni (Or), 6 Mar 2020 - Tentato omicidio quest\u2019oggi a Sagama, (Or) in localit\u00e0 \u201cNuratolu, ai danni di Marcello Zucca di 48 anni allevatore, da parte di 4 persone.<\/p>\n<p>Zucca \u00e8 stato aggredito con violenza e colpito con una roncola al cranio ed al volto.<\/p>\n<p>Due degli aggressori sono stati gi\u00e0 identificati, fermati e portati in caserma a Suni mentre altri due in corso di identificazione e ricercati nel territorio del comune di Tresnuraghes.<\/p>\n<p>Sul posto sono intervenuti per primi carabinieri della Stazione Suni e poi i colleghi del Norm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suni (Or), 6 Mar 2020 &#8211; Tentato omicidio quest\u2019oggi a Sagama, (Or) in localit\u00e0 \u201cNuratolu, ai danni di Marcello Zucca di 48 anni allevatore, da&#8230;<\/p>\n","protected":false},"author":2,"featured_media":187235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187233"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187233"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/187235"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}