{"id":187071,"date":"2020-04-03T08:14:33","date_gmt":"2020-04-03T06:14:33","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=187071"},"modified":"2020-04-03T08:14:33","modified_gmt":"2020-04-03T06:14:33","slug":"coronavirus-oltre-50mila-morti-nel-mondo-raggiunto-un-milione-di-casi","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/03\/coronavirus-oltre-50mila-morti-nel-mondo-raggiunto-un-milione-di-casi\/","title":{"rendered":"Coronavirus, oltre 50mila morti nel mondo. Raggiunto un milione di casi"},"content":{"rendered":"<p>Roma, 3 Apr 2020 - Almeno un milione di persone nel mondo sono state contagiate dal Coronavirus da quando \u00e8 partita l'epidemia. Lo indicano i dati raccolti dai ricercatori della Johns Hopkins University.<\/p>\n<p>\u00c8 presumibile che la reale portata della pandemia sia significativamente maggiore, dal momento che si sospetta che molti Paesi confermino meno contagi di quelli che in realt\u00e0 hanno e perch\u00e9 in altri non sono disponibili i tamponi. I dati dell'istituto si basano sulle comunicazioni ufficiali, oltre che sulle notizie di stampa e altre fonti.<\/p>\n<p>La maggior parte nei casi c'\u00e8 stata finora negli Stati Uniti, con almeno 234.462 contagi, mentre anche Italia e Spagna hanno superato la soglia dei 100 mila. Dopo ci sono la Germania, che ha ufficializzato 84.264 casi, e la Cina, dove \u00e8 iniziata l'epidemia e che ha avuto almeno 82.432 casi.<\/p>\n<p>Nel mondo ci sono almeno 51 mila morti per Coronavirus e l'Italia da questo punto di vista \u00e8 il Paese che finora ha pagato il tributo pi\u00f9 pesante, con quasi 14 mila morti. Il Covid-19 nel complesso ha colpito 181 Paesi e territori, secondo la Johns Hopkins University.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 3 Apr 2020 &#8211; Almeno un milione di persone nel mondo sono state contagiate dal Coronavirus da quando \u00e8 partita l&#8217;epidemia. Lo indicano i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":186980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187071"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=187071"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/187071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=187071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=187071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=187071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}