{"id":186966,"date":"2020-04-01T20:13:17","date_gmt":"2020-04-01T18:13:17","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=186966"},"modified":"2020-04-01T20:13:17","modified_gmt":"2020-04-01T18:13:17","slug":"coronavirus-aggiornamento-dei-dati-alla-sera-del-1-aprile-745-i-casi-di-positivita-al-virus-covid-19-accertati-in-sardegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2020\/04\/01\/coronavirus-aggiornamento-dei-dati-alla-sera-del-1-aprile-745-i-casi-di-positivita-al-virus-covid-19-accertati-in-sardegna\/","title":{"rendered":"Coronavirus, aggiornamento dei dati alla sera del 1 aprile: 745 i casi di positivit\u00e0 al virus Covid-19 accertati in Sardegna."},"content":{"rendered":"<p>Cagliari, 1 aprile 2020 \u2013\u00a0Sono 745 i casi di positivit\u00e0 al virus Covid-19 accertati in Sardegna dall'inizio dell'emergenza.<\/p>\n<p>\u00c8 quanto rilevato dall'Unit\u00e0 di crisi regionale nell'ultimo aggiornamento. In totale nell\u2019Isola sono stati eseguiti 5.501 test. I pazienti ricoverati in ospedale sono in tutto 146, di cui 27 in terapia intensiva, mentre 529 sono le persone in isolamento domiciliare. Il dato progressivo dei casi positivi comprende 21 pazienti guariti, pi\u00f9 altri 15 guariti clinicamente. Salgono a 34 i decessi.<\/p>\n<p>Sul territorio, dei 745 casi positivi complessivamente accertati, 116 sono stati registrati nella Citt\u00e0 Metropolitana di Cagliari (+5 rispetto al dato precedente), 58 nel Sud Sardegna, 15 (+5) a Oristano, 59 (+2) a Nuoro, 497 (+11) a Sassari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 1 aprile 2020 \u2013\u00a0Sono 745 i casi di positivit\u00e0 al virus Covid-19 accertati in Sardegna dall&#8217;inizio dell&#8217;emergenza. \u00c8 quanto rilevato dall&#8217;Unit\u00e0 di crisi regionale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":185638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/186966"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=186966"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/186966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/185638"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=186966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=186966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=186966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}