{"id":174727,"date":"2019-06-01T19:31:58","date_gmt":"2019-06-01T17:31:58","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174727"},"modified":"2019-06-01T19:31:58","modified_gmt":"2019-06-01T17:31:58","slug":"lettera-ue-di-maio-e-salvini-tagliare-tasse-europa-rispetti-volonta-di-crescere","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/lettera-ue-di-maio-e-salvini-tagliare-tasse-europa-rispetti-volonta-di-crescere\/","title":{"rendered":"Lettera Ue, Di Maio e Salvini: &#8220;Tagliare tasse, Europa rispetti volont\u00e0 di crescere&#8221;"},"content":{"rendered":"<p>Roma, 1 Giu 2019 - \"Sono soddisfatto\" della lettera dell'Italia all'Ue \"perch\u00e9 ci sono segnali positivi per l'economia italiana e sono convinto che l'Europa rispetter\u00e0 la nostra volont\u00e0 di crescere e tagliare le tasse\". Lo ha detto a Potenza il vicepremier Matteo Salvini annunciando che luned\u00ec sar\u00e0 \"a inaugurare il primo tratto della Pedemontana veneta\". Il leader della Lega \u00e8 nel capoluogo lucano a sostegno del candidato sindaco, Mario Guarente, che nel ballottaggio del 9 giugno sfider\u00e0 Valerio Tramutoli (Basilicata possibile).<\/p>\n<p>\"La settimana prossima user\u00f2 il consenso che voi mi avete dato non per chiedere una poltrona in pi\u00f9 in Italia, chi se ne frega, ma per dire a Bruxelles: lasciateci lavorare come gli italiani ci chiedono, 'meno tasse e pi\u00f9 lavoro'. E se ci diranno 'no' vedremo chi avr\u00e0 la testa pi\u00f9 dura\". Sulla questione fiscale, il leader della Lega ha aggiunto che \"l'obiettivo del 15% di tasse \u00e8 possibile\".<\/p>\n<p>\"Oggi la giornata comincia bene. Nella lettera scritta dal Mef all'Ue \u00e8 stato cancellato il passaggio che prevedeva tagli alla spesa sociale. L'unica cosa da tagliare sono le tasse ai cittadini. Un altro governo Monti anche no, ne abbiamo avuto abbastanza! Ringrazio il ministro Tria per aver provveduto a correggere. Del resto non potevamo accettare altre sforbiciate lacrime e sangue. Resta da capire a chi sia venuta in mente questa bizzarra idea circolata nelle bozze e se quel passaggio sia stato concordato, politicamente, con qualcuno\".<\/p>\n<p>La Commissione Europea ha \"ricevuto la\u00a0lettera\" inviata ieri dal ministro dell'Economia Giovanni Tria, in cui\u00a0si illustrano i 'fattori rilevanti', i motivi per i quali l'Italia non\u00a0ha rispettato la regola del debito nel 2018, come gi\u00e0 nel 2017 e nel\u00a02016. \"Ora la includeremo nella nostra valutazione complessiva\". Lo\u00a0dice una portavoce dell'esecutivo comunitario.<\/p>\n<p>A proposito, invece, della Festa della Repubblica e delle polemiche sorte a proposito della parata, il vicepremier commenta: \"Alla parata del 2 giugno ci sar\u00f2 e sar\u00f2 al fianco delle Forze armate credo sia dovere di un ministro essere sempre al fianco delle proprie donne e dei propri uomini, se qualcuno non c'\u00e8 \u00e8 perch\u00e9 non ha sentito sempre questa vicinanza\".<\/p>\n<p>Mentre sul sul 'caso Palamara' il vicepremier ha dichiarato: \"La riforma della giustizia \u00e8 urgente. Non entro nel merito ma - ha aggiunto - da cittadino italiano, non \u00e8 normale che ci siano magistrati che indagano altri magistrati e che ci siano accuse di corruzione su chi dovrebbe giudicare i cittadini. Spero che emergano in fretta eventuali responsabilit\u00e0. La riforma della giustizia, al servizio dei cittadini, \u00e8 un'emergenza in questo Paese\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 1 Giu 2019 &#8211; &#8220;Sono soddisfatto&#8221; della lettera dell&#8217;Italia all&#8217;Ue &#8220;perch\u00e9 ci sono segnali positivi per l&#8217;economia italiana e sono convinto che l&#8217;Europa rispetter\u00e0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":158689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174727"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174727"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/158689"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}