{"id":174717,"date":"2019-06-01T19:08:55","date_gmt":"2019-06-01T17:08:55","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174717"},"modified":"2019-06-01T19:08:55","modified_gmt":"2019-06-01T17:08:55","slug":"vertenza-latte-tavolo-ministeriale-presso-prefettura-di-sassari-con-lassessore-regionale-allagricoltura-della-regione-saredegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/vertenza-latte-tavolo-ministeriale-presso-prefettura-di-sassari-con-lassessore-regionale-allagricoltura-della-regione-saredegna\/","title":{"rendered":"Vertenza latte: tavolo ministeriale presso prefettura di Sassari con l&#8217;assessore regionale all&#8217;Agricoltura della Regione Sardegna"},"content":{"rendered":"<p>Cagliari, 1 Giu 2019\u00a0- Si \u00e8 tenuta nella mattinata di ieri, 31 maggio 2019, nei locali della Prefettura di Sassari, la riunione del tavolo governativo sulla vertenza del settore lattiero-caseario, alla presenza del Prefetto di Sassari, Maria Luisa D\u2019alessandro, del capo di Gabinetto del Ministro delle Politiche agricole, consigliere luigi fiorentino, e dell\u2019assessore regionale regionale dell\u2019agricoltura, Gabriella Murgia.<\/p>\n<p>In apertura dell\u2019incontro, il capo di Gabinetto ha espresso il proprio apprezzamento per gli obiettivi raggiunti, grazie al lavoro svolto nei mesi scorsi, con particolare riferimento alle misure contenute nel decreto-legge 29 marzo 2019, n. 27, c. d. emergenze, recentemente convertito in legge 21 maggio 2019, n. 44, recante, tra le altre, disposizioni urgenti per il rilancio del settore lattiero-caseario del comparto del latte ovi-caprino.<\/p>\n<p>In un clima di collaborazione interistituzionale, le parti hanno convenuto sulla necessit\u00e0 di procedere al monitoraggio delle intese raggiunte nel corso degli incontri tenutisi a febbraio-marzo 2019 e sull\u2019importanza dell\u2019attuazione delle disposizioni contenute nel suddetto decreto legge.<\/p>\n<p>A tal proposito, il Prefetto e il capo di Gabinetto hanno rappresentato l\u2019importanza di una partecipazione propositiva, e il pi\u00f9 possibile condivisa, da parte dei vari attori della filiera, soprattutto con riferimento alla redazione dei previsti decreti ministeriali.<\/p>\n<p>Al riguardo, \u00e8 stata richiesta alle rappresentanze del comparto e dei pastori di formulare per iscritto delle proposte puntuali, da trasmettere al Ministero dell\u2019agricoltura, sia in ordine ai decreti attuativi, sia sulle modalit\u00e0 di attuazione della norma relativa al c.d. fondo indigenti.<\/p>\n<p>Il Prefetto e il capo di Gabinetto, d\u2019intesa con l\u2019assessore regionale Gabriella Murgia, hanno concordato sulla prosecuzione del tavolo governativo, soprattutto con riguardo alla fase di attuazione dei decreti ministeriali e, pi\u00f9 in generale, al monitoraggio della filiera.<\/p>\n<p>Il capo dell\u2019esecutivo Solinas, ha inoltre assicurato l\u2019attivazione, per quanto di competenza, di appositi tavoli regionali di analisi, approfondimento e per la formulazione di proposte migliorative. La riconvocazione del tavolo governativo avverr\u00e0 una volta pervenute le proposte concernenti le questioni trattate nel corso della seduta.<\/p>\n<p>I rappresentanti delle organizzazioni professionali, datoriali e dei pastori hanno condiviso l\u2019impostazione seguita ed espresso apprezzamento per quanto fin qui fatto, richiedendo, al contempo, l\u2019attivazione del tavolo di filiera nazionale. E\u2019 stata, inoltre, rappresentata l\u2019esigenza di procedere ad attivare appositi tavoli con la grande distruzione organizzata, con l\u2019Istituto per commercio estero, relativamente all\u2019internazionalizzazione della produzione, e, infine, con le forze armate e altre amministrazioni con riguardo alla possibilit\u00e0 di utilizzo del pecorino.<\/p>\n<p>Nel corso del pomeriggio, conclude la nota, si \u00e8 tenuto un incontro con i rappresentati del Consorzio per la tutela del pecorino romano in ordine alle modifiche statutarie e del disciplinare nonch\u00e9 alla revisione del nuovo piano di regolamentazione dell\u2019offerta. Si \u00e8 trattato soltanto di un primo momento di confronto che proseguir\u00e0 nell\u2019ambito dell\u2019assemblea del consorzio. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 1 Giu 2019\u00a0&#8211; Si \u00e8 tenuta nella mattinata di ieri, 31 maggio 2019, nei locali della Prefettura di Sassari, la riunione del tavolo governativo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174717"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174717"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174138"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}