{"id":174715,"date":"2019-06-01T17:06:19","date_gmt":"2019-06-01T15:06:19","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174715"},"modified":"2019-06-01T17:06:19","modified_gmt":"2019-06-01T15:06:19","slug":"guardia-di-finanza-cagliari-societa-edile-evade-il-fisco-per-oltre-430-mila-euro","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/guardia-di-finanza-cagliari-societa-edile-evade-il-fisco-per-oltre-430-mila-euro\/","title":{"rendered":"Guardia di finanza Cagliari: societ\u00e0 edile evade il fisco per oltre 430 mila Euro."},"content":{"rendered":"<p>Cagliari, 1 Giu 2019 - Nell\u2019ambito delle attivit\u00e0 di contrasto all\u2019evasione fiscale, i militari della Seconda Compagnia di Cagliari ha concluso una verifica fiscale nei confronti di una societ\u00e0, con sede operativa in Quartu Sant\u2019 Elena, che non ha dichiarato, per gli anni d\u2019imposta dal 2015 al 2017, ricavi per oltre 432.509 euro.<\/p>\n<p>Nella circostanza, l\u2019azione dei Finanzieri \u00e8 stata orientata alla verifica del corretto adempimento delle disposizioni tributarie ai fini dell\u2019I.V.A., delle imposte dirette e degli altri tributi.<\/p>\n<p>In questo caso la societ\u00e0, operante nel settore delle ristrutturazioni edilizie, \u00e8 risultata aver eseguito numerosi lavori edili per i quali ha percepito i relativi pagamenti tramite bonifici finalizzati a consentire ai committenti privati le detrazioni fiscali previste.<\/p>\n<p>I successivi incroci dei bonifici in entrata sui conti correnti bancari con la contabilit\u00e0 della societ\u00e0, hanno evidenziato il reale volume d\u2019affari per le annualit\u00e0 verificate constatando ricavi non dichiarati per 432.509 euro ed un\u2019IVA dovuta per 59.390 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 1 Giu 2019 &#8211; Nell\u2019ambito delle attivit\u00e0 di contrasto all\u2019evasione fiscale, i militari della Seconda Compagnia di Cagliari ha concluso una verifica fiscale nei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":154290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174715"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174715"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/154290"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}