{"id":174702,"date":"2019-06-01T15:03:39","date_gmt":"2019-06-01T13:03:39","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174702"},"modified":"2019-06-01T15:03:39","modified_gmt":"2019-06-01T13:03:39","slug":"automobilista-di-orotelli-coinvolto-in-un-incidente-stradale-sotto-linfluenza-dellalcol-denunciato-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/automobilista-di-orotelli-coinvolto-in-un-incidente-stradale-sotto-linfluenza-dellalcol-denunciato-dai-carabinieri\/","title":{"rendered":"Automobilista di Orotelli coinvolto in un incidente stradale sotto l\u2019influenza dell\u2019alcol; denunciato dai carabinieri."},"content":{"rendered":"<p>Orotelli (Nu), 1 Giu 2019 - I Carabinieri della Stazione di Orotelli, hanno denunciato un 20enne di Orgosolo che, a bordo della propria autovettura, \u00e8 rimasto coinvolto in un incidente stradale scontrandosi frontalmente con un\u2019altra auto che proveniva dal senso opposto.<\/p>\n<p>L\u2019atteggiamento del conducente non \u00e8 sfuggito ai militari intervenuti sul posto per i rilievi e, infatti, all\u2019esito degli esami effettuati presso l\u2019ospedale San Francesco di Nuoro, \u00e8 emerso che il tasso alcolemico riscontrato era pi\u00f9 alto del limite consentito.<\/p>\n<p>Il conducente quindi \u00e8 stato sanzionato poi e denunciato in stato di libert\u00e0 alla competente Autorit\u00e0 Giudiziaria, per guida in stato di ebrezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orotelli (Nu), 1 Giu 2019 &#8211; I Carabinieri della Stazione di Orotelli, hanno denunciato un 20enne di Orgosolo che, a bordo della propria autovettura, \u00e8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174702"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174702"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174703"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}