{"id":174700,"date":"2019-06-01T13:03:24","date_gmt":"2019-06-01T11:03:24","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174700"},"modified":"2019-06-01T13:03:24","modified_gmt":"2019-06-01T11:03:24","slug":"rinviati-a-giudizio-82-appartenenti-al-gruppo-ultras-del-cagliari-calcio","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/rinviati-a-giudizio-82-appartenenti-al-gruppo-ultras-del-cagliari-calcio\/","title":{"rendered":"Rinviati a giudizio 82 appartenenti al gruppo ultras del \u201cCagliari Calcio\u201d"},"content":{"rendered":"<p>Sassari, 1 Giu 2019 - La Procura della Repubblica presso il Tribunale di Sassari ha chiesto il rinvio a giudizio di 82 appartenenti al gruppo ultras del \u201cCagliari Calcio\u201d, \u201csconvolts\u201d, per i gravi disordini commessi in citt\u00e0 il 25 marzo 2017 in occasione dell\u2019incontro amichevole tra le rappresentative del Sorso 1930 e del Cagliari 1920 disputato presso lo stadio di Sorso. Le richieste sono state avanzate al termine di lunghe ed articolate indagini svolte dalla Digos di Sassari in sinergia con la DIGOS cagliaritana e coordinate dalla locale Procura della Repubblica.<\/p>\n<p>I reati contestati sono particolarmente gravi: devastazione e saccheggio in concorso, con l\u2019aggravante del numero delle persone, lesioni anche gravi e il possesso di artifizi pirotecnici e altri oggetti contundenti e atti ad offendere in occasione di manifestazioni sportive. Inoltre, per 64 ultras cagliaritani, il Questore di Sassari subito dopo gli scontri aveva adottato il provvedimento amministrativo del Daspo con durata da quattro a sei anni.<\/p>\n<p>In quel giorno, circa 180 ultras cagliaritani, affiliati alla cosiddetta frangia degli \u201csconvolts\u201d, diretti a Sorso a bordo di tre pullman per assistere alla partita, avevano poi deciso di fermarsi in via Padre Zirano nei pressi della Stazione ferroviaria di Sassari, essendo poi emerso nel corso delle indagini che tale sosta rifletteva in realt\u00e0 un piano ben preciso il cui fine era quello di devastare, saccheggiare ed aggredire in modo indiscriminato e senza alcun ritegno chiunque transitasse nel centro cittadino sfruttando il cd \u201ceffetto sorpresa\u201d, ben sapendo che l\u2019area del centro storico \u00e8 notoriamente frequentata dalle frange ultras della tifoseria sassarese.<\/p>\n<p>E, nota l\u2019atavica rivalit\u00e0 tra la tifoseria cagliaritana e quella della \u201cSef Torres 1903\u201d, che gi\u00e0 in passato era sfociata in violenti scontri, una volta scesi dai pullman, gli ultras cagliaritani avevano iniziato a marciare in modo compatto e completamente travisati verso la Stazione ferroviaria, esplodendo bombe carta e accedendo fumogeni durante il breve tragitto. Una volta raggiunta l\u2019area antistante lo scalo ferroviario, muniti di mazze, bastoni, catene e aste portabandiera, avevano iniziato ad aggredire con inaudita violenza i cittadini presenti in zona e ad innescare dei tafferugli tali da paralizzare completamente il traffico, compresi i mezzi di trasporto pubblico.<\/p>\n<p>La notizia di un fatto cos\u00ec eclatante si era subito diffusa richiamando numerosi sostenitori della \u201cSef Torres\u201d accorsi dal vicino centro storico per affrontare i tifosi avversari. La drammaticit\u00e0 dello scenario venutosi a creare, testimoniata anche da numerose chiamate concitate pervenute al 113 per atti di vandalismo e aggressioni, aveva reso necessario il ricorso a cariche di alleggerimento e all\u2019utilizzo di lacrimogeni al fine di tenere separate le due tifoserie rivali e a scongiurare il rischio di danni ben pi\u00f9 gravi alle persone. Solo la predisposizione da parte del personale di PS in tenuta antisommossa di un adeguato cordone di sicurezza aveva impedito che la folla, venutasi a creare davanti al piazzale della stazione dove erano stati fatti raggruppare gli \u201csconvolts\u201d, potesse tentare un\u2019incursione per giungere allo scontro con quest\u2019ultima tifoseria.<\/p>\n<p>Con grande difficolt\u00e0 gli ultras cagliaritani erano stati poi fatti salire a bordo dei mezzi in modo da farli allontanare velocemente dal teatro degli scontri. Il clima di forte tensione in cui si erano svolte le operazioni di \u201calleggerimento\u201d e di deflusso non avevano permesso di identificare sul posto i numerosi autori dei gravi illeciti commessi, molti dei quali peraltro travisati, pertanto per l\u2019identificazione dei responsabili si era rivelata fondamentale la sinergia operativa con la DIGOS di Cagliari che, una volta fermato il convoglio sulla SS 131 in prossimit\u00e0 del capoluogo dopo che era ripartito da Sassari, era riuscita ad identificare 64 ultras (di cui due minorenni) e a sequestrare varie aste rinforzate e artifizi pirotecnici, nonch\u00e9 diverse dosi di sostanza stupefacente rinvenute a bordo dei pullman.<\/p>\n<p>Il pesante bilancio della giornata di scontri era stato di diversi feriti sia tra i cittadini che tra le Forze dell\u2019Ordine, dovendosi aggiungere anche il danneggiamento di strutture (panchine, muretti, ecc) di propriet\u00e0 del Comune. Per la ricostruzione dei fatti nelle sue varie fasi \u2013 dall\u2019organizzazione del viaggio sino all\u2019identificazione dei tifosi di rientro a Cagliari - e per l\u2019individuazione delle responsabilit\u00e0 ci si \u00e8 inoltre avvalsi dell\u2019analisi dei tabulati telefonici e delle immagini registrate dagli impianti di videosorveglianza del Comune di Sassari presenti nei luoghi dei disordini, delle riprese della Polizia Scientifica, nonch\u00e9 dei contributi offerti da vari video amatoriali postati su internet e pubblicati sul sito della \u201cNuova Sardegna\u201d; materiale che \u00e8 stato esaminato con la massima attenzione dal personale della Digos di Sassari in un contesto di reciproca e costante sinergia informativa con l\u2019omologo Ufficio del capoluogo.<\/p>\n<p>Di assoluta utilit\u00e0 investigativa si era rivelato anche il contributo offerto dalla comunit\u00e0, espresso dalle numerose denunce\/querele e dalle preziose testimonianze dei cittadini raccolte in seguito agli scontri, che hanno permesso, insieme alla visione dei filmati e ad altre fonti di prova, di risalire agli 82 indagati colpiti dalle odierne richieste di rinvio a giudizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari, 1 Giu 2019 &#8211; La Procura della Repubblica presso il Tribunale di Sassari ha chiesto il rinvio a giudizio di 82 appartenenti al gruppo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174700"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174700"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174700\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}