{"id":174692,"date":"2019-06-01T12:25:17","date_gmt":"2019-06-01T10:25:17","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174692"},"modified":"2019-06-01T12:25:17","modified_gmt":"2019-06-01T10:25:17","slug":"giovane-arrestato-per-il-possesso-di-sostanze-stupefacenti-di-vario-tipo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/06\/01\/giovane-arrestato-per-il-possesso-di-sostanze-stupefacenti-di-vario-tipo\/","title":{"rendered":"Giovane arrestato per il possesso di sostanze stupefacenti di vario tipo"},"content":{"rendered":"<p>Oristano, 1 Giu 2019 - Nell\u2019ambito di attivit\u00e0 per la repressione dei reati inerenti lo spaccio di sostanze stupefacenti e indirizzate soprattutto al quartiere Torangius, il personale della Squadra Mobile hanno arrestato P.G.L., di 26 anni, residente a Simaxis, trovato, a seguito di perquisizione personale, in possesso di diversi tipi di sostanze illecite.<\/p>\n<p>Il giovane, da tempo monitorato dagli agenti della Polizia, alla vista degli agenti si \u00e8 mostrato particolarmente nervoso, anche perch\u00e9, come in seguito riscontrato, aveva appena venduto una dose di cocaina ad un altro ragazzo il quale, a sua volta, \u00e8 stato denunciato all\u2019Autorit\u00e0 Amministrativa perch\u00e9 consumatore di sostanze stupefacenti.<\/p>\n<p>A seguito delle perquisizioni, estese anche alle abitazioni dei due giovani, sono stati rinvenuti alcuni contenitori con all\u2019interno dell\u2019infiorescenza di marijuana essiccata e diverse decine di grammi di hashish nonch\u00e9 dieci dosi di cocaina, quattro dosi di eroina, diversi bilancini di precisione e la somma in contante di circa 1500 euro che l\u2019arrestato aveva al seguito.<\/p>\n<p>Di particolare interesse investigativo \u00e8 ritenuto essere un libretto riportante un elenco con su indicati \u201cDebiti Vecchi\u201d e \u201cdebitori nuovi\u201d dettagliatamente descritto e sicuramente riferibile alla contabilit\u00e0 dell\u2019attivit\u00e0 illecita di spaccio posta in essere dall\u2019arrestato.<\/p>\n<p>Il giovane, posto immediatamente a disposizione dell\u2019Autorit\u00e0 Giudiziaria, verr\u00e0 condotto innanzi al Giudice per la convalida dell\u2019arresto.<\/p>\n<p>Da diverso tempo gli agenti della Questura sono impegnati in servizi di prevenzione e repressione del traffico di sostanze stupefacenti, interessando non solo la citt\u00e0 di Oristano ma anche il resto della provincia, attivit\u00e0 che, nell\u2019ultimo periodo, ha permesso di denunciare in stato di libert\u00e0 anche altri due giovani residenti a Oristano per il reato di detenzione ai fini di spaccio di cocaina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oristano, 1 Giu 2019 &#8211; Nell\u2019ambito di attivit\u00e0 per la repressione dei reati inerenti lo spaccio di sostanze stupefacenti e indirizzate soprattutto al quartiere Torangius,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174692"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174692"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174693"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}