{"id":174663,"date":"2019-05-31T15:06:45","date_gmt":"2019-05-31T13:06:45","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174663"},"modified":"2019-05-31T15:06:45","modified_gmt":"2019-05-31T13:06:45","slug":"i-carabinieri-della-compagnia-di-jerzu-passano-al-setaccio-gli-ovili-della-zona-allevatore-di-perdasdefogu-sanzionato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/31\/i-carabinieri-della-compagnia-di-jerzu-passano-al-setaccio-gli-ovili-della-zona-allevatore-di-perdasdefogu-sanzionato\/","title":{"rendered":"I carabinieri della compagnia di Jerzu passano al setaccio gli ovili della zona: allevatore di Perdasdefogu sanzionato."},"content":{"rendered":"<p>Jerzu (Nu), 31 Magg 2019 - I Carabinieri della Compagnia di Jerzu continuano con incisivit\u00e0 l\u2019attivit\u00e0 di controllo negli ovili del territorio di competenza.<\/p>\n<p>Nell\u2019ambito di un vasto servizio finalizzato anche alla verifica della normativa di settore, i militari della Squadriglia Anticrimine dei cc, hanno sanzionato un allevatore 51enne di Perdasdefogu poich\u00e9, all\u2019interno dell\u2019ovile di sua propriet\u00e0, erano presenti ben 8 bovini adulti non identificati mediante i previsti marchi e mai registrati alla Banca Dati Nazionale delle Anagrafi nazionali zootecniche. E, quindi, il pastore \u00e8 stato sanzionato per una cifra di 4.000 Euro.<\/p>\n<p>Considerata la delicatezza del settore, anche in relazione al pericolo che animali vaganti si riversino sulle strade, i servizi continueranno su tutto il territorio della Compagnia di Jerzu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jerzu (Nu), 31 Magg 2019 &#8211; I Carabinieri della Compagnia di Jerzu continuano con incisivit\u00e0 l\u2019attivit\u00e0 di controllo negli ovili del territorio di competenza. Nell\u2019ambito&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174663"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174663"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174659"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}