{"id":174551,"date":"2019-05-29T17:40:47","date_gmt":"2019-05-29T15:40:47","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174551"},"modified":"2019-05-29T17:40:47","modified_gmt":"2019-05-29T15:40:47","slug":"accordo-air-italy-alitalia-su-olbia-presidente-solinas-accolta-nostra-proposta-di-mediazione","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/29\/accordo-air-italy-alitalia-su-olbia-presidente-solinas-accolta-nostra-proposta-di-mediazione\/","title":{"rendered":"Accordo air Italy-Alitalia su Olbia, presidente Solinas: \u201caccolta nostra proposta di mediazione\u201d"},"content":{"rendered":"<p>Cagliari, 29 Magg 2019\u00a0- \u201cPossiamo dare con soddisfazione la notizia che Air Italy e Alitalia hanno aderito alla proposta di mediazione formulata dalla Regione per garantire a Olbia e a tutto il territorio gallurese la presenza di Air Italy, con la salvaguardia del diritto al lavoro di oltre 500 persone, e finalmente anche il diritto a programmare una stagione turistica degna di questo nome\u201d.<\/p>\n<p>Lo fa sapere con una nota il presidente della Regione, Christian Solinas, stamattina a Villa Devoto, a margine della presentazione di Connect, il forum del trasporto aereo in programma a Cagliari dal 5 al 7 giugno 2019, ha commentato l\u2019accordo raggiunto dalle due compagnie sui voli da Olbia in continuit\u00e0 territoriale per Roma Fiumicino e Milano Linate. \u201cAvremo voli e frequenze che verranno condivisi da Air Italy e Alitalia\u201d, ha sottolineato Solinas. \u201cRisolviamo cos\u00ec uno dei principali nodi legati ai trasporti, e anche sociali, che si erano proposti in questi mesi\u201d.\u00a0Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 29 Magg 2019\u00a0&#8211; \u201cPossiamo dare con soddisfazione la notizia che Air Italy e Alitalia hanno aderito alla proposta di mediazione formulata dalla Regione per&#8230;<\/p>\n","protected":false},"author":2,"featured_media":172886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174551"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174551"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/172886"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}