{"id":174397,"date":"2019-05-24T16:58:48","date_gmt":"2019-05-24T14:58:48","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174397"},"modified":"2019-05-24T16:58:48","modified_gmt":"2019-05-24T14:58:48","slug":"sanita-assessore-nieddu-incontra-sindacati-lavoratori-comparto-poste-le-basi-per-un-confronto-costante","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/24\/sanita-assessore-nieddu-incontra-sindacati-lavoratori-comparto-poste-le-basi-per-un-confronto-costante\/","title":{"rendered":"Sanit\u00e0: Assessore Nieddu incontra sindacati lavoratori comparto: poste le basi per un confronto costante"},"content":{"rendered":"<p>Cagliari, 24 Magg 2019\u00a0- Questa mattina, negli uffici dell\u2019assessorato regionale della Sanit\u00e0, l\u2019assessore Mario Nieddu ha incontrato i rappresentanti delle sigle sindacali regionali della funzione pubblica di Cgil, Cisl e Uil e la federazione dei sindacati indipendenti FSI USAE. Al centro dei due incontri, avvenuti separatamente, la riforma del sistema sanitario regionale e la situazione dei lavoratori del comparto.<\/p>\n<p>\u201cHo ritenuto utile \u2013 spiega in una nota l\u2019assessore Nieddu \u2013\u00a0soprattutto in questa fase, incontrare i sindacati, per chiarire la linea di questo assessorato e porre le basi di un confronto che non dovr\u00e0 mai mancare, nel pieno rispetto delle norme contrattuali. Le difficolt\u00e0 che il nostro sistema sanitario attraversa pesano in maniera rilevante sugli operatori del comparto. Criticit\u00e0 che il personale sta affrontando ormai da tempo con professionalit\u00e0 e spirito di servizio. Supportare gli operatori significa supportare i cittadini e i territori, per cui la nostra attenzione \u00e8 massima\u201d. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 24 Magg 2019\u00a0&#8211; Questa mattina, negli uffici dell\u2019assessorato regionale della Sanit\u00e0, l\u2019assessore Mario Nieddu ha incontrato i rappresentanti delle sigle sindacali regionali della funzione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174397"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174397"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174398"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}