{"id":174389,"date":"2019-05-24T15:20:59","date_gmt":"2019-05-24T13:20:59","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174389"},"modified":"2019-05-24T15:20:59","modified_gmt":"2019-05-24T13:20:59","slug":"accordo-regione-sardegna-e-compagnia-aerea-air-italy-dichiarazione-del-consigliere-regionale-roberto-li-gioi-m5s","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/24\/accordo-regione-sardegna-e-compagnia-aerea-air-italy-dichiarazione-del-consigliere-regionale-roberto-li-gioi-m5s\/","title":{"rendered":"Accordo Regione Sardegna e compagnia aerea Air Italy: dichiarazione del Consigliere regionale Roberto Li Gioi (M5S)."},"content":{"rendered":"<p>Cagliari, 24 Magg 2019 - \u201cL\u2019accordo raggiunto tra la Regione e Air Italy \u00e8 senza dubbio una notizia positiva nell\u2019immediato perch\u00e9 tutela temporaneamente il diritto al lavoro dei 600 dipendenti della compagnia. Tuttavia, come lamentato anche dai sindacati, restiamo in attesa di un piano industriale credibile, che continua invece a mancare. Lo dichiara in una nota stampa il consigliere regionale Roberto Li Gioi (M5S) alla luce delle ultime notizie riguardo la continuit\u00e0 territoriale.<\/p>\n<p>\u201cL\u2019epilogo della vicenda, purtroppo \u2013 si legge ancora nella nota - fa accrescere i dubbi sull\u2019affidabilit\u00e0 del management della compagnia ex Meridiana, in quanto, qualche settimana fa la proposta accolta in queste ore era stata invece rifiutata. E come se non bastasse, Air Italy avrebbe inoltre chiesto alla compagnia di bandiera di coprire un volo in pi\u00f9 per carenza di aeromobili\u201d.<\/p>\n<p>\u201cQuindi \u2013 conclude Li Gioi - sicuramente non vengono eliminati i dubbi che nell\u2019immediato futuro i vertici di Air Italy possano cogliere ulteriori pretesti per scaricare nuovamente i lavoratori. Per questo motivo, \u00e8 obbligatorio che la Giunta regionale si metta subito al lavoro per costruire un nuovo bando sulla continuit\u00e0 territoriale che non lasci il minimo spazio ad azioni strumentali\u201d. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 24 Magg 2019 &#8211; \u201cL\u2019accordo raggiunto tra la Regione e Air Italy \u00e8 senza dubbio una notizia positiva nell\u2019immediato perch\u00e9 tutela temporaneamente il diritto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174389"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174389"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/174390"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}