{"id":174173,"date":"2019-05-19T12:09:10","date_gmt":"2019-05-19T10:09:10","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174173"},"modified":"2019-05-19T12:09:10","modified_gmt":"2019-05-19T10:09:10","slug":"truffa-sui-fondi-agricoli-denunciati-tre-imprenditori-agricoli-dai-militari-della-guardia-di-finanza","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/19\/truffa-sui-fondi-agricoli-denunciati-tre-imprenditori-agricoli-dai-militari-della-guardia-di-finanza\/","title":{"rendered":"Truffa sui fondi agricoli: denunciati tre imprenditori agricoli dai militari della Guardia di Finanza."},"content":{"rendered":"<p>Cagliari, 19 Magg 2019 - Nel corso di un\u2019attivit\u00e0 delegata dalla locale Autorit\u00e0 Giudiziaria, condotta dalle Fiamme Gialle del Comando Provinciale di Cagliari, i Finanzieri del Nucleo di Polizia Economico Finanziaria hanno denunciato 3 imprenditori agricoli - appartenenti allo stesso nucleo familiare e riconducibili a due aziende del settore primario, operanti nel comune di Muravera - ed accertato una frode a valere sui fondi che l\u2019Unione europea mette a disposizione per la valorizzazione ed il sostegno delle attivit\u00e0 imprenditoriali in campo agricolo.<\/p>\n<p>Le indagini hanno permesso di accertare che gli imprenditori agricoli, a fronte delle istanze presentate, hanno ottenuto indebitamente 175.765 euro di contributi (dal 2005 al 2018), attraverso false dichiarazioni, attestanti l\u2019esistenza di un titolo giuridico di conduzione dei terreni, di cui \u00e8 stata appurata successivamente la mancanza.<\/p>\n<p>Per i tre soggetti \u00e8, quindi, scattata la denuncia all\u2019Autorit\u00e0 Giudiziaria, con l\u2019accusa di truffa aggravata per il conseguimento di erogazioni pubbliche.<\/p>\n<p>Inoltre, la condotta illecita degli imprenditori ha avuto rilievo sia sotto il profilo del danno erariale - con conseguente segnalazione alla Procura Regionale della Corte dei conti -, sia sotto il profilo della normativa sanzionatoria speciale, che prevede la contestazione della sanzione amministrativa pari al contributo erogato. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 19 Magg 2019 &#8211; Nel corso di un\u2019attivit\u00e0 delegata dalla locale Autorit\u00e0 Giudiziaria, condotta dalle Fiamme Gialle del Comando Provinciale di Cagliari, i Finanzieri&#8230;<\/p>\n","protected":false},"author":2,"featured_media":168739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174173"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174173"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}