{"id":174118,"date":"2019-05-17T15:25:30","date_gmt":"2019-05-17T13:25:30","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=174118"},"modified":"2019-05-17T15:25:30","modified_gmt":"2019-05-17T13:25:30","slug":"gdf-tenenza-iglesias-datore-di-lavoro-non-versa-oltre-6-000-euro-di-ritenute-sui-redditi-del-dipendente-denunciato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/17\/gdf-tenenza-iglesias-datore-di-lavoro-non-versa-oltre-6-000-euro-di-ritenute-sui-redditi-del-dipendente-denunciato\/","title":{"rendered":"Gdf Tenenza Iglesias &#8211; Datore di lavoro non versa oltre 6.000 euro di ritenute sui redditi del dipendente, denunciato"},"content":{"rendered":"<p>Iglesias, 17 Magg 2019 - \u00a0Nell\u2019ambito delle attivit\u00e0 di contrasto all\u2019evasione fiscale, le Fiamme Gialle della Tenenza di Iglesias hanno concluso un controllo fiscale nei confronti di una ditta con sede in Carbonia, operante nel settore della riparazione e manutenzione di autovetture.<\/p>\n<p>Nella circostanza, l\u2019azione dei militari della Guardia di Finanza di Iglesias, \u00e8 stata orientata all\u2019accertamento della presenza di eventuali lavoratori \u201cin nero\u201d o irregolari nonch\u00e9 alla verifica degli adempimenti previsti dalle normative fiscali relativi alla tenuta delle scritture contabili da parte del datore di lavoro quale sostituto d\u2019imposta e sulle ritenute operate dallo stesso sui redditi da lavoro corrisposti ai dipendenti.<\/p>\n<p>L\u2019attivit\u00e0 ispettiva ha permesso di rilevare che, per gli anni d\u2019imposta 2016, 2017, 2018 e 2019, \u00e8 stato omesso il versamento delle ritenute d\u2019acconto ai fini Irpef operate sulle buste paga, a fronte di stipendi e T.F.R. corrisposti al personale dipendente, per un importo complessivo pari a 6.428 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iglesias, 17 Magg 2019 &#8211; \u00a0Nell\u2019ambito delle attivit\u00e0 di contrasto all\u2019evasione fiscale, le Fiamme Gialle della Tenenza di Iglesias hanno concluso un controllo fiscale nei&#8230;<\/p>\n","protected":false},"author":2,"featured_media":153380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174118"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=174118"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/174118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/153380"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=174118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=174118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=174118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}