{"id":173995,"date":"2019-05-14T19:12:58","date_gmt":"2019-05-14T17:12:58","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=173995"},"modified":"2019-05-14T19:12:58","modified_gmt":"2019-05-14T17:12:58","slug":"accordo-huawei-zedda-sardegna-verso-formazione-continua-e-qualita-fasolino-la-sardegna-in-direzione-del-traguardo-di-prima-smart-region-in-europa","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/14\/accordo-huawei-zedda-sardegna-verso-formazione-continua-e-qualita-fasolino-la-sardegna-in-direzione-del-traguardo-di-prima-smart-region-in-europa\/","title":{"rendered":"Accordo Huawei: Zedda, Sardegna verso formazione continua e qualit\u00e0. Fasolino, la Sardegna in direzione del traguardo di prima Smart Region in Europa"},"content":{"rendered":"<p>Roma, 14 Magg 2019\u00a0\u2013 \u201cLa vera sfida per la Sardegna \u00e8 l'innovazione. La nostra crescita economica deve basarsi su forti investimenti nel campo delle nuove tecnologie, e sullo sviluppo delle competenze digitali. Dobbiamo formare la forza lavoro orientandola verso le nuove professioni per soddisfare il fabbisogno delle imprese\u201d.<\/p>\n<p>Lo scrive in una nota l\u2019assessore del Lavoro Alessandra Zedda, commentando l\u2019accordo di partnership con Huawei, sottoscritto stamane a Roma a margine dei lavori del Forum Pa.<\/p>\n<p>\u201cOggi\u00a0registriamo un gap tra domanda e offerta di lavoro nei settori tecnologici, basti pensare che circa 45.000 posizioni lavorative restano scoperte per la mancanza di competenze. La Regione - prosegue l\u2019esponente dell\u2019esecutivo - deve perci\u00f2 intervenire puntando sulla formazione continua e di qualit\u00e0, e l'accordo siglato con Huawei academy va in questa direzione. Anche le nostre universit\u00e0 devono essere al passo con il mercato del lavoro, aumentando i corsi in ambito tecnico e ingegneristico per formare i lavoratori digitali del\u00a0domani, che siano in grado di occuparsi dei settori emergenti: dall'intelligenza artificiale, all'economia circolare e all'internet delle cose. Lo sforzo dunque deve essere globale, per un nuovo approccio delle politiche del lavoro che guarda al digitale, partendo dalla formazione.\"<\/p>\n<p>\"Diamo finalmente gambe all'accordo tra Regione Sardegna, Crs4 e Huawei, - conclude l\u2019assessore Zedda - che ha portato alla creazione dell'innovation center\u201d, commenta l'assessore della Programmazione Giuseppe Fasolino. \u201cL'intervento per la realizzazione della Huawei academy ci permette di partire con la formazione in ambito digitale, cos\u00ec da rafforzare le professionalit\u00e0 in grado di supportare il processo di digitalizzazione. La Sardegna si candida per diventare la prima Smart Region in Europa, grazie agli investimenti nei settori delle Ict. Vogliamo essere una regione all'avanguardia, che sposa la conversione digitale come ricetta per lo sviluppo dei nostri territori. Abbiamo le risorse per farlo, per investire in questa transizione e realizzare un modello di crescita intelligente\u201d. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 14 Magg 2019\u00a0\u2013 \u201cLa vera sfida per la Sardegna \u00e8 l&#8217;innovazione. La nostra crescita economica deve basarsi su forti investimenti nel campo delle nuove&#8230;<\/p>\n","protected":false},"author":2,"featured_media":173997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/173995"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=173995"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/173995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/173997"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=173995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=173995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=173995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}