{"id":173932,"date":"2019-05-13T09:47:46","date_gmt":"2019-05-13T07:47:46","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=173932"},"modified":"2019-05-13T09:47:46","modified_gmt":"2019-05-13T07:47:46","slug":"ballottaggi-ieri-domenica-in-sicilia-i-cinque-stelle-fanno-il-pieno","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2019\/05\/13\/ballottaggi-ieri-domenica-in-sicilia-i-cinque-stelle-fanno-il-pieno\/","title":{"rendered":"Ballottaggi ieri, domenica, in Sicilia: i Cinque Stelle fanno il pieno"},"content":{"rendered":"<p>Cagliari, 13 Magg 2019 \u2013 Grande soddisfazione per il M5s nel risultato elettorale dei ballottaggi in Sicialia. Ed ora cercher\u00e0 di monetizzare per le europee del 26 maggio, mentre resta a mani vuote la Lega che perde la doppia sfida, seppure di misura, con i suoi candidati e non riesce a fare lo sgambetto nell'isola agli 'alleati' grillini.<\/p>\n<p>L'esito dei ballottaggi in Sicilia, dove si \u00e8 votato in cinque comuni, fa segnare l'en plein dei 5stelle, che vincono in due citt\u00e0 emblematiche, dopo avere perso Bagheria e Gela conquistate cinque anni fa: Caltanissetta, ancora stravolta dallo scandalo del cosiddetto 'sistema Montante', l'ex presidente di Sicindustria condannato due giorni fa a 14 anni di carcere e che proprio dalla citt\u00e0 nissena aveva scalato i piani alti del potere; e Castelvetrano, la cittadina dei superlatitante Matteo Messina Denaro, chiamata al voto dopo due anni di commissariamento per infiltrazioni mafiose.<\/p>\n<p>Una vittoria celebrata su Facebook in nottata, quando lo spoglio era a met\u00e0 ma dall'esito scontato, dal vice premier Luigi Di Maio: \"Abbiamo vinto con il nostro candidato Roberto Gambino\", quando ci danno per morti noi ci siamo sempre\". E nel pomeriggio Di Maio sar\u00e0 a Caltanissetta per festeggiare, assieme al padrone di casa Giancarlo Cancelleri, la vittoria di Gambino,che ha ottenuto il 58,85%, staccando il rivale Michele Giarratana, del centrodestra, che si \u00e8 fermato al 41,15%. Una festa doppia perch\u00e9 con Di Maio, a Caltanissetta, ci sar\u00e0 pure Enzo Alfano, eletto nuovo sindaco a Castelvetrano: il grillino al ballottaggio ha totalizzato il 64,67% dei voti, quasi\u00a0il doppio dell'avversario civico Calogero Martire (35,33%).<\/p>\n<p>A bocca asciutta la Lega, che si deve accontentare del solo comune di Motta Sant'Anastasia, appena 12mila abitanti conquistato al primo turno: i suoi candidati Giuseppe Spata e Giorgio Randazzo perdono i duelli a Gela (Caltanissetta) e a Mazara del Vallo (Trapani) nonostante le piazze riempite da Salvini durante il suo tour elettorale: qui vincono Salvatore Quinci (52,41%) del centrosinistra, ma sostenuto anche da liste civiche e moderati, e Lucio Greco (52,45%), appoggiato da Forza Italia e liste civiche. A Monreale, invece, vince Alberto Arcidiacono, sostenuto da liste civiche e da Diventer\u00e0 Bellissima, il movimento del governatore Nello Musumeci: col 55,73% ha sconfitto l'uscente Piero Capizzi (44,27%).<\/p>\n<p>Bassa l'affluenza nei cinque comuni, pari al 43,60%, con un calo del 15,37% rispetto al primo turno. Ai seggi si sono recati 98.783 elettori sui 226.546 aventi diritto. Il crollo maggiore a Gela, dove ha votato il 40,49% degli elettori rispetto al 58,41%del primo turno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 13 Magg 2019 \u2013 Grande soddisfazione per il M5s nel risultato elettorale dei ballottaggi in Sicialia. Ed ora cercher\u00e0 di monetizzare per le europee&#8230;<\/p>\n","protected":false},"author":2,"featured_media":173933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/173932"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=173932"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/173932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/173933"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=173932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=173932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=173932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}