{"id":165945,"date":"2018-10-16T18:08:42","date_gmt":"2018-10-16T16:08:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=165945"},"modified":"2018-10-16T18:08:42","modified_gmt":"2018-10-16T16:08:42","slug":"giunta-sardegna-le-altre-delibere-di-oggi-31","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2018\/10\/16\/giunta-sardegna-le-altre-delibere-di-oggi-31\/","title":{"rendered":"Giunta Sardegna: le altre delibere di oggi"},"content":{"rendered":"<p>Cagliari, 16 Ott 2018 -\u00a0La Giunta regionale, riunita nel pomeriggio a Villa Devoto sotto la presidenza di Francesco Pigliaru, ha autorizzato il trasferimento all\u2019Agenzia Laore Sardegna di 1milione 271mila e 448,45euro, per l\u2019esercizio finanziario 2018, con l\u2019impegno di accreditarli all\u2019Associazione provinciale allevatori (APA) di Oristano per l\u2019attuazione del programma sulla Tenuta dei libri genealogici e dei Controlli funzionali sulle razze animali per l\u2019anno in corso. Le risorse saranno destinate all\u2019APA di Oristano quale ufficio unico periferico istituito dall\u2019Associazione italiana allevatori (AIA).<br \/>\nSempre su proposta dell\u2019assessore dell\u2019Agricoltura, Pier Luigi Caria, la Giunta ha \u00a0inoltre approvato il rendiconto della gestione 2017 dell\u2019Agenzia Argea Sardegna, mentre per l\u2019Agenzia Laore Sardegna ha licenziato il rendiconto per la gestione 2017 e approvato l\u2019elenco analitico delle risorse vincolate sempre del 2017.<br \/>\nProtezione dati. In tema trattamento dei dati personali e libera circolazione di tali dati, su proposta della Presidenza sono state approvate le modifiche alla deliberazione n. 21\/8 del 2018 - che definisce le misure di governance e procedimentali applicabili all'Amministrazione regionale - per contemplare la gestione della violazione della sicurezza dei dati (c.d. data breach).<br \/>\nAmbiente - A seguito dell\u2019ordinanza del capo del Dipartimento della Protezione civile nazionale, via libera ai contributi ai soggetti privati per i danni occorsi alle attivit\u00e0 economiche e produttive causati dagli eventi alluvionali del 2015. La delibera individua l\u2019iter istruttorio, le modalit\u00e0 tecniche per la gestione delle domande di contributo e la relativa modulistica. Approvato inoltre il Conto consuntivo e bilancio economico-patrimoniale 2017 di Arpas.<\/p>\n<p>Istruzione. Su proposta di delibera dell\u2019assessore della Pubblica Istruzione e Cultura Giuseppe Dessena, \u00e8 stato deciso dall\u2019Esecutivo che la quota del risultato di amministrazione del Consiglio di amministrazione dell\u2019Ersu di Sassari, pari a 7milioni 582mila euro, venga cos\u00ec ripartita: 5,5 milioni saranno destinati a interventi di impiantistica sportiva e valorizzazione dei beni culturali come campagne di scavi, restauri ed emergenze archeologiche; 2 milioni 82mila euro resteranno nella disponibilit\u00e0 dell\u2019Ersu e saranno utilizzati 1 milione per l\u2019ex Fondazione Brigata Sassari e 1 milione 73mila euro per borse di studio e altri servizi dedicati agli studenti universitari.<\/p>\n<p>Lavori Pubblici \u2013 Su proposta dell\u2019assessore dei Lavori Pubblici Edoardo Balzarini, la Giunta ha approvato la rimodulazione degli interventi di edilizia popolare nei comuni di Goni, Guspini, Muravera, San Nicol\u00f2 Gerrei, Silius e Uta. In quest\u2019ultimo si \u00e8 resa necessaria la riduzione a 4 alloggi rispetto al primo progetto, che ne prevedeva 6. Con le economie derivanti, saranno completate le opere di sistemazione esterna degli alloggi di Guspini, Muravera e Silius. La Giunta ha inoltre stabilito di assegnare le risorse regionali destinate al Fondo sociale - e quantificate per il 2018 in 270.000 euro - \u00a0all\u2019Azienda Regionale per l\u2019Edilizia Abitativa (AREA). Si tratta di risorse stanziate annualmente per il pagamento di contributi a favore di assegnatari in condizioni di indigenza, che non possono pagare il canone o altre spese di amministrazione e manutenzione, che vengono destinate ad AREA in quanto detiene l\u201985% del patrimonio ERP e di conseguenza gestisce la stessa percentuale di assegnatari di alloggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 16 Ott 2018 &#8211;\u00a0La Giunta regionale, riunita nel pomeriggio a Villa Devoto sotto la presidenza di Francesco Pigliaru, ha autorizzato il trasferimento all\u2019Agenzia Laore&#8230;<\/p>\n","protected":false},"author":2,"featured_media":157921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/165945"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=165945"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/165945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/157921"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=165945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=165945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=165945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}