{"id":164375,"date":"2018-09-10T19:52:22","date_gmt":"2018-09-10T17:52:22","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=164375"},"modified":"2018-09-10T19:52:22","modified_gmt":"2018-09-10T17:52:22","slug":"rasporti-trasferimento-lavoratori-air-italy-careddu-mills-non-parla-di-crescita-in-sardegna-attendiamo-qatar-airways","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2018\/09\/10\/rasporti-trasferimento-lavoratori-air-italy-careddu-mills-non-parla-di-crescita-in-sardegna-attendiamo-qatar-airways\/","title":{"rendered":"Rasporti, trasferimento lavoratori Air Italy. Careddu: Mills non parla di crescita in Sardegna, attendiamo Qatar Airways"},"content":{"rendered":"<p>Cagliari, 10 Sett 2016 -\u00a0\u201cNemmeno un riferimento alla crescita della base di Olbia, non un richiamo a investimenti con ricadute dirette nell\u2019isola bens\u00ec la perseveranza nel confermare i 51 irragionevoli trasferimenti a Malpensa: le dichiarazioni odierne del chief operations officer di Air Italy, Neil Mills, e il suo tempismo imperfetto ci convincono ulteriormente della necessit\u00e0 di avere un rapporto diretto con l\u2019azionista della Compagnia cos\u00ec come gi\u00e0 richiesto all\u2019ambasciatore del Qatar\u201d.<\/p>\n<p>Lo dice l\u2019assessore dei Trasporti Carlo Careddu. \u201cA questo punto attendiamo la visita della delegazione di Qatar Airways in\u00a0Sardegna cosi come proposto dall\u2019esponente diplomatico per apprendere i dettagli\u00a0di un piano industriale che parli finalmente di uno sviluppo della compagnia anche nell\u2019isola con una conseguente crescita della forza lavoro e dei collegamenti, non solo in termini di continuit\u00e0 territoriale e chiediamo la sospensione dei trasferimenti a Malpensa\u201d. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 10 Sett 2016 &#8211;\u00a0\u201cNemmeno un riferimento alla crescita della base di Olbia, non un richiamo a investimenti con ricadute dirette nell\u2019isola bens\u00ec la perseveranza&#8230;<\/p>\n","protected":false},"author":2,"featured_media":145602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/164375"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=164375"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/164375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/145602"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=164375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=164375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=164375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}