{"id":153307,"date":"2018-01-10T19:13:52","date_gmt":"2018-01-10T18:13:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=153307"},"modified":"2018-01-10T19:13:52","modified_gmt":"2018-01-10T18:13:52","slug":"prevenzione-giunta-sardegna-approva-riordino-centri-diagnosi-tumore-della-mammella","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2018\/01\/10\/prevenzione-giunta-sardegna-approva-riordino-centri-diagnosi-tumore-della-mammella\/","title":{"rendered":"Prevenzione, Giunta Sardegna approva riordino centri diagnosi tumore della mammella"},"content":{"rendered":"<p>Cagliari, 10 Gen 2018\u00a0- La Regione avvia il riordino dei centri dedicati alla diagnostica del tumore della mammella, con Linee di Indirizzo approvate\u00a0oggi\u00a0dalla Giunta.<\/p>\n<p>\u201cAttualmente, in Sardegna - spiega l\u2019assessore della Sanit\u00e0, Luigi Arru - non esiste una rete formalizzata di Centri di diagnostica clinica per la senologia conforme ai criteri dell\u2019Intesa Stato \u2013 Regioni del 2014. Esistono molte strutture, pubbliche e private che erogano prestazioni di tipo senologico, collocate su tutto il territorio regionale e che operano per lo pi\u00f9 in assenza di un volume di casi adeguato rispetto agli standard raccomandati dalle linee guida e dai protocolli screening. \u00c8 perci\u00f2 importante identificare, a livello regionale, i Centri di diagnostica clinica, che operino in integrazione e a supporto dei Centri individuati come sedi di Breast Unit a Cagliari, Nuoro e Sassari e migliorare l\u2019intero percorso diagnostico e terapeutico del tumore mammario, a partire dalla diagnosi precoce. Vogliamo promuovere il progressivo innalzamento dei tassi di adesione ai Programmi organizzati di screening oncologico: i dati del 2016 evidenziano come solo 58 donne su 100 aventi diritto (cosiddetta popolazione bersaglio annua, ricompresa nella fascia di et\u00e0 50 \u2013 69 anni) hanno ricevuto l\u2019invito ad effettuare la mammografia e solo 23 donne su 100 aventi diritto hanno effettivamente usufruito del test di screening\u201d.<\/p>\n<p>Il dimensionamento della rete dei Centri di diagnostica clinica e la loro distribuzione nel territorio regionale, in base alle Linee di Indirizzo, si basa sul bacino di utenza regionale (popolazione femminile nella fascia di et\u00e0 a maggiore rischio \u2013 compresa tra i 50 e i 69 anni) articolato per Area Socio Sanitaria Locale dell\u2019ATS Sardegna; sul volume teorico annuo di prestazioni, sugli standard raccomandati dalle linee guida per la diagnostica clinica senologica e dai protocolli screening, sia in termini di volumi di prestazioni mammografiche che di procedure interventistiche.<\/p>\n<p>Per assicurare alle strutture dei territori periferici (che non dispongono di una casistica sufficiente o comunque inferiore allo standard minimo di garanzia della qualit\u00e0 dell\u2019esito) di valorizzare le professionalit\u00e0 presenti sul territorio e utilizzare in modo pi\u00f9 efficiente, a livello regionale, sia le risorse umane, sia le risorse tecnologiche e strumentali, e\u0300 introdotto un ulteriore criterio di tipo organizzativo l\u2019\u201cequipe unica di professionisti\u201d che dovr\u00e0 essere costituita necessariamente tra le ASSL di Nuoro \u2013 Lanusei e di Cagliari-Sanluri.<\/p>\n<p>Su proposta dell\u2019assessore Arru, la Giunta ha approvato anche il Programma formativo regionale per gli operatori coinvolti nello screening del carcinoma del colon retto e dato all\u2019Ats gli indirizzi operativi per l\u2019aggiornamento dell\u2019assistenza integrativa alla luce dei nuovi Lea (Livelli Essenziali di Assistenza). Red-com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 10 Gen 2018\u00a0&#8211; La Regione avvia il riordino dei centri dedicati alla diagnostica del tumore della mammella, con Linee di Indirizzo approvate\u00a0oggi\u00a0dalla Giunta. \u201cAttualmente,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":142230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/153307"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=153307"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/153307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/142230"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=153307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=153307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=153307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}