{"id":153103,"date":"2018-01-05T18:53:30","date_gmt":"2018-01-05T17:53:30","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=153103"},"modified":"2018-01-05T18:53:30","modified_gmt":"2018-01-05T17:53:30","slug":"industria-7-start-up-sarde-al-ces-di-las-vegas-e-il-gruppo-piu-numeroso-della-delegazione-italiana-di-imprese-innovative-pigliaru-e-piras-investiamo-nei-giovani-talenti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2018\/01\/05\/industria-7-start-up-sarde-al-ces-di-las-vegas-e-il-gruppo-piu-numeroso-della-delegazione-italiana-di-imprese-innovative-pigliaru-e-piras-investiamo-nei-giovani-talenti\/","title":{"rendered":"Industria, 7 start up sarde al Ces di Las Vegas. \u00c8 il gruppo pi\u00f9 numeroso della delegazione italiana di imprese innovative. Pigliaru e Piras: investiamo nei giovani talenti"},"content":{"rendered":"<p>Cagliari, 5 Gen 2018\u00a0\u2013 La Sardegna che vola a Las Vegas per l\u2019edizione 2018 del CES, l\u2019evento mondiale dedicato all\u2019hi-tech, un record lo ha gi\u00e0 stabilito: \u00e8 la regione italiana con il numero pi\u00f9 alto di start up innovative presenti alla manifestazione. Su un totale di 40 imprese, che dal 9 al 12 gennaio saranno ospitate in uno spazio esclusivo dedicato ai prodotti tecnologicamente avanzati, le start up isolane selezionate dagli organizzatori sono ben 7 (inizialmente erano otto, ma una ha rinunciato alla vigilia della partenza). Sul palcoscenico del CES, che quest\u2019anno ospita quasi 4 mila espositori, si appresta a salire una \u2018squadra\u2019 compatta di giovani imprenditori sardi, ognuno con i propri dispositivi e i propri progetti. Rappresentano l\u2019avanguardia di un settore che \u00e8 cresciuto in questi anni.<\/p>\n<p>Se si guarda, infatti, alla Relazione Annuale al Parlamento sullo stato d\u2019attuazione e l\u2019impatto delle policy a sostegno di startup e PMI innovative presentato dal Ministro Calenda a giugno di quest\u2019anno, la Sardegna \u00e8 al 15\u00b0 posto nella classifica delle regioni italiane per peso percentuale delle startup innovative sul totale nazionale e al 12\u00b0 per incidenza startup innovative sul totale delle societ\u00e0 di capitali attive. \u00c8 al 17\u00b0 posto nella classifica delle regioni italiane per numero di startup in ambito energetico, con 17 start up su 1.115 nazionali. Quanto alla posizione delle province, Cagliari (non Sud Sardegna) \u00e8 al 19\u00b0 posto per l\u2019Incidenza startup innovative sull\u2019intera popolazione di societ\u00e0 di capitali attive. Per quanto riguarda la distribuzione regionale delle operazioni di finanziamento erogate verso startup innovative dal Fondo di Garanzia per le PMI, con 6.787.400 euro per 28 operazioni e una media di 242.407 euro a operazione, la Sardegna si colloca al 6\u00b0 posto per dimensione di operazioni; mentre \u00e8 al 16\u00b0 quanto a incidenza per regione sull\u2019accesso delle startup al Fondo Garanzia PMI con il 9,1% e al 15\u00b0 posto per numero di PMI Innovative. In riferimento a Smart&amp;Start Italia, il programma di finanza agevolata diretto alle startup innovative di tutta Italia gestito da Invitalia, l\u2019Agenzia nazionale per l\u2019attrazione degli investimenti e lo sviluppo d\u2019impresa, la Sardegna con 40 domande presentate e quasi 20 milioni di euro richiesti, rappresenta il 3% su base nazionale. Il rapporto 2017 dell\u2019Osservatorio del Politecnico di Milano propone un\u2019analisi sugli investitori nell\u2019equity crowdfunding italiano dalla quale risulta che oltre il 20% degli investitori persona fisica \u00e8 residente in Lombardia. Seguono le Marche, con il 13%, e la Sardegna, con il 9,5%. La Regione Sardegna punta a rafforzare la crescita delle start up costituitesi negli ultimi anni tramite le numerose iniziative di promozione all\u2019estero intraprese in questi ultimi anni. Dopo l\u2019organizzazione, in collaborazione con ICE Agenzia, del Forum ICT Sardinia, iniziativa tenutasi nell\u2019ambito di Sinnova nell\u2019ottobre 2016, dove sono stati promossi incontri B2B tra investitori internazionali selezionati provenienti da 20 Paesi e 70 aziende ICT sarde, di cui circa un terzo startup innovative, e dopo la missione a Singapore e Los Angeles a novembre 2017, le 7 start up isolane saranno a Las Vegas grazie al Programma di Internazionalizzazione, varato dalla Giunta Pigliaru ed elaborato e gestito dall\u2019Assessorato dell\u2019Industria. Il Programma ha messo in campo oltre 16 milioni di euro per consentire alle imprese sarde, con un focus specifico su quelle dell\u2019ICT e dell\u2019agroalimentare, di aprirsi ai mercati esteri e attrarre nuovi investitori. A queste risorse si sono aggiunte quelle che, annualmente, sono destinate all\u2019organizzazione di missioni all\u2019estero, sempre in collaborazione con ICE Agenzia. A partire, inoltre da fine 2017, le imprese sarde possono inoltre partecipare alle iniziative organizzate all\u2019interno del Piano Export Sud II gestito da ICE, in collaborazione con la Regione. Per le start up presenti al CES \u00e8 previsto non solo il rimborso delle spese di viaggio e alloggio, ma anche il rimborso delle spese di realizzazione del materiale promozionale, la predisposizione dei prototipi e il restyling dei siti web.<\/p>\n<p>\u201cSviluppo significa individuare i punti di forza e sostenerli nella crescita \u2013 spiega il presidente della Regione Francesco Pigliaru \u2013 e nelle start up innovative la Sardegna ha chiaramente un punto di forza: abbiamo una storia tecnologica importante, buone Universit\u00e0 che sfornano giovani competenti e, non ultimo, questo genere di aziende produce beni che non soffrono degli svantaggi causati dall\u2019insularit\u00e0, perch\u00e9 nell\u2019ambito digitale le barriere geografiche smettono di esistere. Promuovere e rafforzare le start up e le PMI innovative soprattutto all\u2019estero \u2013 prosegue il presidente Pigliaru \u2013 \u00e8 un processo positivo che per noi \u00e8 essenziale consolidare: facciamo di tutto per aiutarle con aiuti economici mirati e con un Programma di Internazionalizzazione ambizioso che sta dando i suoi frutti, come dimostra una presenza cos\u00ec importante al CES di Las Vegas. Investire energie e risorse in questa direzione \u00e8 una scelta giusta \u2013 conclude Francesco Pigliaru \u2013 significa creare le condizioni perch\u00e9 i giovani sardi di talento possano pensare a un futuro in Sardegna\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-151806 alignleft\" src=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2017\/12\/Assessora-Piras-Gadon-1-300x200.jpg\" alt=\"Assessora Piras - Gadon\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2017\/12\/Assessora-Piras-Gadon-1-300x200.jpg 300w, https:\/\/www.cronacaonline.it\/wp-content\/uploads\/2017\/12\/Assessora-Piras-Gadon-1.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u201cIl fatto che un quinto delle start up innovative italiane presenti all\u2019evento di Las Vegas sia rappresentato da aziende sarde, la dice lunga sulla vitalit\u00e0 di questo settore nella nostra regione. Si tratta \u2013 afferma l\u2019assessora dell\u2019Industria, Maria Grazia Piras \u2013 di imprese che hanno idee e competenze sviluppatesi in Sardegna, dove si contano tantissime esperienze legate alla ricerca e all\u2019innovazione. Penso agli incubatori che fanno capo alle universit\u00e0 e ad alcune realt\u00e0 imprenditoriali ormai consolidate. Il nostro compito, come Assessorato, \u00e8 consentire alle imprese, soprattutto quelle pi\u00f9 giovani e impegnate nella sfida delle nuove tecnologie, di avere gli strumenti opportuni per misurarsi con i grandi mercati internazionali. Il programma triennale di Internazionalizzazione varato tre anni fa, e che nell\u2019ottobre scorso abbiamo aggiornato al 2018-2020, ha gi\u00e0 dato buoni risultati, in particolare per quanto riguarda l\u2019export delle aziende agro-alimentari. Ci aspettiamo buoni risultati anche per l\u2019ICT, che nell\u2019isola ha numeri consistenti, sia per numero di imprese che per numero di addetti. La partecipazione delle aziende del settore alle recenti iniziative di novembre, a Los Angeles e Singapore, \u00e8 stata positiva. Ci sono tutte le premesse \u2013 conclude l\u2019assessora \u2013 perch\u00e9 lo stesso accada anche a Las Vegas\u201d.<\/p>\n<p>Delle 7 start up che andranno a Las Vegas, quattro sono di Cagliari, due di Sassari e una di Lanusei. Autentico, societ\u00e0 cagliaritana che produce software, presenter\u00e0 un sistema innovativo di etichettatura certificata anti frode. Veranu, start up gi\u00e0 vincitrice di numerosi premi, porta negli USA la mattonella che produce energia. Un albero tecnologico in grado di sfruttare l\u2019energia del sole e trasformare l\u2019aria in acqua \u00e8 invece il prodotto ideato dalla start up ogliastrina Life Tree. Bautiful Box, prodotto dalla Bautiful di Cagliari, \u00e8 il prodotto grazie al quale \u00e8 possibile controllare e intrattenere da remoto gli animali domestici. Il monitoraggio e la cura a distanza delle piante da appartamento sono invece il punto di forza del dispositivo creato dalla sassarese Lifely. Non pu\u00f2 mancare un prodotto di realt\u00e0 aumentata, in questo caso Brave Potions, che permette ai bambini di vincere la \u2018paura\u2019 dei medici. Infine, la start up sassarese Cube Controls che presenter\u00e0 a Las Vegas una linea innovativa di joystick per giochi elettronici. Red-com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 5 Gen 2018\u00a0\u2013 La Sardegna che vola a Las Vegas per l\u2019edizione 2018 del CES, l\u2019evento mondiale dedicato all\u2019hi-tech, un record lo ha gi\u00e0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":151073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/153103"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=153103"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/153103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/151073"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=153103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=153103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=153103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}