{"id":152729,"date":"2017-12-23T18:46:37","date_gmt":"2017-12-23T17:46:37","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=152729"},"modified":"2017-12-23T18:46:37","modified_gmt":"2017-12-23T17:46:37","slug":"siccita-comparto-agricolo-e-apistico-giunta-sardegna-vota-richiesta-di-declatoria-da-inviare-al-mipaaf-per-accesso-a-provvidenze-del-fondo-di-solidarieta-nazionale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/12\/23\/siccita-comparto-agricolo-e-apistico-giunta-sardegna-vota-richiesta-di-declatoria-da-inviare-al-mipaaf-per-accesso-a-provvidenze-del-fondo-di-solidarieta-nazionale\/","title":{"rendered":"Siccit\u00e0 &#8211; Comparto agricolo e apistico: Giunta Sardegna vota richiesta di declatoria da inviare al Mipaaf per accesso a provvidenze del fondo di solidariet\u00e0 nazionale"},"content":{"rendered":"<p>Cagliari, 23 Dic 2017 \u2013\u00a0Su proposta dell\u2019assessore dell\u2019Agricoltura, Pier Luigi Caria, la Giunta ha licenziato nei giorni scorsi la delibera, destinata al Ministero delle Politiche agricole alimentari e forestali, per il riconoscimento del carattere eccezionale sulla prolungata siccit\u00e0 della primavera-estate 2017, che ha interessato l\u2019intero territorio regionale, per i danni alle colture orticole, cerealicole, di leguminose da granella, frutticole, viticole, olivicole e per le produzioni del comparto apistico. Si chiede quindi al Ministero che vengano attivate, per tutte le aziende interessate, le provvidenze previste dall\u2019art. 5 del decreto legislativo 102 del 2004 e gli interventi attraverso il Fondo di solidariet\u00e0 nazionale (FSN).<\/p>\n<p>Le provvidenze. Per favorire la ripresa economica e produttiva delle imprese colpite dalla siccit\u00e0 possono essere concessi: contributi in conto capitale per i danni alle produzioni e alle scorte aziendali; possono essere prorogate per una sola volta e per non pi\u00f9 di 24 mesi le scadenze delle rate delle operazioni di credito agrario di esercizio e di miglioramento e di credito ordinario effettuate dalle imprese agricole; pu\u00f2 essere concesso l'esonero parziale (dal 17% fino a un massimo del 50%) del pagamento dei contributi previdenziali e assistenziali propri e per i lavoratori dipendenti, in scadenza nei dodici mesi successivi alla data in cui si \u00e8 verificato l'evento. Tali aiuti possono essere attivati in forma singola o combinata, tenuto conto della dotazione finanziaria assegnata al Fondo.<\/p>\n<p>La siccit\u00e0. La nuova declaratoria arriva dopo i primi interventi emergenziali sul versante della siccit\u00e0 che lo scorso 27 settembre sono stati presentati al Mipaaf dalla Regione Sardegna per il riconoscimento dei danni alle produzioni foraggere delle aziende zootecniche di tutta l\u2019Isola. Tale richiesta \u00e8 stata poi accolta un mese dopo dal Ministero. Sugli altri comparti agricoli, poich\u00e9 l\u2019evento non si era ancora concluso ed erano ancora in corso le attivit\u00e0 di verifica dei danni alle colture da parte dell\u2019Agenzia Argea Sardegna, si sta intervenendo invece in questi giorni. Dalla relazione sugli accertamenti in campo emerge che la siccit\u00e0 e l\u2019eccesso di calore hanno colpito le colture in atto su tutto il territorio regionale, con danni che hanno intensit\u00e0 variabili tra il 40% e il 50% per quelle in irriguo e tra il 60% e il 70% in quelle in asciutto, a seconda che le superfici ricadano o meno all\u2019interno dei comprensori coperti dalla rete dei Consorzi di Bonifica. Particolarmente negativi sono stati inoltre gli effetti della prolungata siccit\u00e0 anche sulle produzioni apistiche che si sono notevolmente ridotte, con un danno medio accertato pari all\u201980%. Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 23 Dic 2017 \u2013\u00a0Su proposta dell\u2019assessore dell\u2019Agricoltura, Pier Luigi Caria, la Giunta ha licenziato nei giorni scorsi la delibera, destinata al Ministero delle Politiche&#8230;<\/p>\n","protected":false},"author":2,"featured_media":138295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152729"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=152729"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/138295"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=152729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=152729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=152729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}