{"id":152727,"date":"2017-12-23T18:45:04","date_gmt":"2017-12-23T17:45:04","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=152727"},"modified":"2017-12-23T18:45:04","modified_gmt":"2017-12-23T17:45:04","slug":"riorganizzazione-comunicazione-regione-sardegna-nessun-indebolimento-ma-primo-passaggio-di-un-piano-piu-ampio-per-rendere-la-regione-piu-forte-ed-efficiente","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/12\/23\/riorganizzazione-comunicazione-regione-sardegna-nessun-indebolimento-ma-primo-passaggio-di-un-piano-piu-ampio-per-rendere-la-regione-piu-forte-ed-efficiente\/","title":{"rendered":"Riorganizzazione comunicazione regione Sardegna, nessun indebolimento ma primo passaggio di un piano pi\u00f9 ampio per rendere la regione pi\u00f9 forte ed efficiente"},"content":{"rendered":"<p>Cagliari, 23 Dic 2017.\u00a0\u201cLa Giunta Regionale ha in corso un processo di riforma organizzativa destinata a rafforzare le strutture evitando sprechi e duplicazioni, creando anche una chiara separazione tra organi di gestione ed autorit\u00e0 di controllo. Queste necessit\u00e0 sono state pi\u00f9 volte all'attenzione delle forze politiche e sollecitate in Consiglio Regionale. Sulla improrogabilit\u00e0\u00a0della riorganizzazione io stesso sono intervenuto in occasione del dibattito sulla manovra finanziaria in via di approvazione all'Assemblea regionale su richiesta espressa dell'opposizione consiliare. Per questa ragione deve essere chiaro che la riorganizzazione della Comunicazione \u00e8 solo il primo passaggio di una serie di ulteriori atti che snelliranno la macchina per migliorarne l'efficienza complessiva\u201d. Lo ha detto l\u2019assessore degli Affari Generali e del Personale Filippo Spanu replicando ad alcune valutazioni che riguardano il futuro immediato della Direzione generale della Comunicazione della Regione Sardegna.<\/p>\n<p>\u201cLa Giunta \u2013 aggiunge Spanu - non vuole indebolire la struttura del servizio Comunicazione, questo deve essere chiaro; anzi verr\u00e0 consolidata la struttura e rafforzata, con l'inserimento nella Direzione generale della Presidenza, Direzione tecnica e non politica. Allo stesso tempo\u00a0procederemo a rendere indipendente dalla gestione l'ufficio per la Trasparenza e l'Anticorruzione, guidato fino ad\u00a0oggi\u00a0dalla dottoressa Michela Melis che con la sua autorevolezza ne ha garantito la forza e lo sviluppo in una fase embrionale. Anche per questo alla stessa dottoressa Melis va tutta la nostra gratitudine nel momento in cui dopo decenni di apprezzato servizio, lascia l'Amministrazione\u201d.<\/p>\n<p>\u201cNelle prossime settimane \u2013conclude la nota dell\u2019assessore degli Affari Generali - altri passi verranno compiuti in questo senso al fine di garantire una Regione pi\u00f9 efficiente. L'esperienza di coloro che denunciano oscuri ed improbabili complotti \u00e8 troppa per non capire il senso di questa operazione che non indebolisce la Comunicazione, non la commissaria e, \u00e8 bene sottolinearlo, manterr\u00e0 la distinzione tra catena tecnica e controllo politico. Per quanto riguarda le elezioni -conclude Spanu- par di ricordare che la creazione della Direzione generale della Comunicazione a pochi mesi dai comizi elettorali, con una guida esterna sostanzialmente politica, fu fatta da altra Giunta non certamente di centrosinistra\u201d. Red-com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 23 Dic 2017.\u00a0\u201cLa Giunta Regionale ha in corso un processo di riforma organizzativa destinata a rafforzare le strutture evitando sprechi e duplicazioni, creando anche&#8230;<\/p>\n","protected":false},"author":2,"featured_media":123401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152727"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=152727"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/123401"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=152727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=152727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=152727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}