{"id":152263,"date":"2017-12-13T14:45:46","date_gmt":"2017-12-13T13:45:46","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=152263"},"modified":"2017-12-13T14:45:46","modified_gmt":"2017-12-13T13:45:46","slug":"trasporti-aerei-continuita-territoriale-ancora-aumenti-sulle-rotte-da-cagliari-per-milano-e-roma-e-su-alghero-linate","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/12\/13\/trasporti-aerei-continuita-territoriale-ancora-aumenti-sulle-rotte-da-cagliari-per-milano-e-roma-e-su-alghero-linate\/","title":{"rendered":"Trasporti aerei, continuit\u00e0 territoriale: ancora aumenti sulle rotte da Cagliari per Milano e Roma e Su Alghero-Linate"},"content":{"rendered":"<p>Cagliari, 13 Dic 2017 -\u00a0Sono 110mila i posti messi in vendita sulle rotte aeree in continuit\u00e0 territoriale operate da Alitalia da Cagliari per Milano e Roma e sulla Alghero-Linate nel periodo dal 20 dicembre al 9 gennaio prossimi. L\u2019incremento complessivo rispetto alle disponibilit\u00e0 ordinarie previste dal decreto di imposizione degli oneri di servizio sfiora ormai il 55%: ovvero, a 70836 poltrone in dotazione di base, ne sono state aggiunte 38685. Pertanto la previsione di posti aggiuntivi pari al 50% decisa nell\u2019ultimo Comitato di monitoraggio Regione-Enac-compagnie convocato dall'assessore dei Trasporti Carlo Careddu il 23 novembre scorso, \u00e8 stata ulteriormente aumentata del 5%.<\/p>\n<p>Tutti i collegamenti dispongono di aerei aggiuntivi (18) e di numerosi upgrade (10). Per esempio, la\u00a0Alghero-Linate-Alghero\u00a0il 23 dicembre arriva ad avere 6 voli con un incremento pari quasi al 200% e 872 posti in vendita, contro i 296 stabili dal decreto. Sulla stessa rotta in 12 giornate su 21 nel periodo indicato l\u2019aumento di capienza supera notevolmente il 100%.\u00a0Cagliari-Fiumicino-Cagliari\u00a0conta su 18 voli nei giorni di picco dal 20 al 23 dicembre con aumenti di posti superiori al 50%: le poltrone in vendita in queste date sono quasi 3300 quotidiane contro le 2136 previste dal contratto di servizio.\u00a0Cagliari-Linate-Cagliari\u00a0raggiunge aumenti del 152% per esempio il 23 dicembre con 20 voli a disposizione e quasi 2900 posti. In 12 giorni sui 21 del periodo preso in considerazione, l\u2019incremento su questo collegamento non \u00e8 mai inferiore alll\u201980%.<\/p>\n<p>\"Questi risultati sono il frutto di una attivit\u00e0 di programmazione in sede di Comitato di controllo e di un costante monitoraggio dell'Assessorato finalizzati a superare le criticit\u00e0 del sistema nei periodi di picco - dice l'assessore Careddu -, nel periodo natalizio viaggeranno da e per l'isola, anche con i collegamenti in continuit\u00e0 territoriale, centinaia di migliaia di sardi e di turisti, certamente stiamo reggendo l'impatto di una domanda massiccia, ma una migliore efficienza e qualit\u00e0 saranno ulteriormente garantite con il nuovo bando\".\u00a0Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 13 Dic 2017 &#8211;\u00a0Sono 110mila i posti messi in vendita sulle rotte aeree in continuit\u00e0 territoriale operate da Alitalia da Cagliari per Milano e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":145602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152263"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=152263"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/152263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/145602"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=152263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=152263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=152263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}