{"id":150001,"date":"2017-10-24T14:36:09","date_gmt":"2017-10-24T12:36:09","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=150001"},"modified":"2017-10-24T14:36:09","modified_gmt":"2017-10-24T12:36:09","slug":"comune-di-cagliari-rinnovo-pass-zone-a-traffico-limitato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/10\/24\/comune-di-cagliari-rinnovo-pass-zone-a-traffico-limitato\/","title":{"rendered":"Comune di Cagliari &#8211; Rinnovo pass Zone a Traffico Limitato"},"content":{"rendered":"<p>Cagliari, 24 Ott 2017 - Dal prossimo 2 novembre parte il servizio per il rinnovo dei permessi di circolazione per le Zone a Traffico Limitato, per le aree riservate e, limitatamente ai pass di servizio, per i parcheggi a pagamento, in scadenza il prossimo 31 dicembre.<br \/>\nI residenti delle ZTL del centro storico in possesso del pass con validit\u00e0 quinquennale, potranno richiedere invece il rinnovo a partire da due mesi prima della data della scadenza indicata sul loro permesso.<br \/>\nGli interessati possono rivolgersi all'Ufficio ZTL al sesto piano del Palazzo Civico in piazza De Gasperi, nei giorni di marted\u00ec, mercoled\u00ec e venerd\u00ec dalle ore 9,30 alle 11,30 oppure\u00a0il marted\u00ec pomeriggio dalle 16,00 alle 17,30. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 24 Ott 2017 &#8211; Dal prossimo 2 novembre parte il servizio per il rinnovo dei permessi di circolazione per le Zone a Traffico Limitato,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":132553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/150001"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=150001"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/150001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/132553"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=150001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=150001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=150001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}