{"id":149999,"date":"2017-10-24T14:33:26","date_gmt":"2017-10-24T12:33:26","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=149999"},"modified":"2017-10-24T14:33:26","modified_gmt":"2017-10-24T12:33:26","slug":"comune-di-cagliari-comincia-il-7-novembre-il-festival-della-scienza-2017","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/10\/24\/comune-di-cagliari-comincia-il-7-novembre-il-festival-della-scienza-2017\/","title":{"rendered":"Comune di Cagliari &#8211; Comincia il 7 novembre il Festival della Scienza 2017"},"content":{"rendered":"<p>Cagliari, 24 Ott 2017 - Vita e macchina, natura e tecnologia, distinte e congiunte allo stesso tempo. \u00c8 l\u2019emblema scelto dagli organizzatori dell\u2019edizione numero 10 del Festival della Scienza che si tiene a Cagliari dal 7 al 12 novembre. Tra l'ExM\u00e0 e il Ghetto di via Santa Croce 18, nel cuore del quartiere Castello.<br \/>\nSotto il titolo \u201cScienza Futura\u201d, il concetto che trova moltissime declinazioni nella \u201cmescolanza di saperi\u201d fra discipline scientifiche e umanistiche, impegner\u00e0 scienziati, divulgatori di livello internazionale. Ma soprattutto oltre 400 studenti delle scuole e dell\u2019universit\u00e0, in pi\u00f9 di 100 appuntamenti tra conferenze e dibattiti, animazioni e spettacoli, letture e presentazioni di libri, percorsi museali, botanici e naturalistici. Punto di forza si confermano anche quest\u2019anno i laboratori interattivi per raccontare, e far raccontare anche ai pi\u00f9 piccoli, la scienza in modo semplice e originale.<br \/>\nCom\u2019\u00e8 nel suo dna, l\u2019Amministrazione comunale risponde quindi ancora presente all\u2019appello fatto dall\u2019associazione Scienza Societ\u00e0 Scienza e concede sostegno e patrocinio alla manifestazione che si \u00e8 presentata\u00a0oggi, marted\u00ec 24 ottobre, alla MEM.<br \/>\nA fare gli onori di casa l\u2019assessore Paolo Frau: \u201cQuello di quest\u2019anno \u00e8 il decimo Festival della Scienza. E al di la del ricco e variegato programma che per sei giorni animer\u00e0 Cagliari, ci\u00f2 rappresenta di per s\u00e9 un titolo di merito perch\u00e9 dimostra una costanza, finanche ostinazione nel campo della divulgazione della cultura attraverso un approccio di tipo scientifico rispetto alla realt\u00e0 che ci circonda e che coinvolge in maniera diretta un esercito di giovani\u201d.<\/p>\n<p>L\u2019organizzazione e la calendarizzazione della sei giorni di Cagliari \u00e8 stata invece illustrata da Carla Romagnino. \u201cAd aprire ufficialmente il Festival sar\u00e0 la cerimonia d\u2019inaugurazione che si terr\u00e0 gioved\u00ec 7 ottobre nell\u2019Aula Magna del Rettorato al civico 32 di via Universit\u00e0 alle 16 a cui seguir\u00e0 la conferenza \u201cGeni, persone e contaminazioni di saperi\u201d a cura di Chiara Zuccato\u201d. Dopodich\u00e9 si svolger\u00e0 in massima parte tra l'ExM\u00e0 e il Ghetto, con escursioni al Teatro Massimo gli spettacoli \u201cScrivere il futuro\u201d e \u201cStarlight settemillimetridiuniverso\u201d.<\/p>\n<p>\u201cIl tema \u201cScienza Futura\u201d di questa edizione \u2013 ha sottolineato Romagnino -\u00a0 si propone di far percorrere a chi vi parteciper\u00e0 le avvincenti avventure che la scienza sta vivendo in questi ultimi anni. Saranno trattati quindi i temi pi\u00f9 attuali e scottanti del dibattito scientifico come quello sui vaccini, che sar\u00e0 affrontato alle 11 all\u2019ExM\u00e0 nella giornata conclusiva del Festival, domenica 12 novembre\u201d.<\/p>\n<p>Dopo Cagliari il Festival proseguir\u00e0 a Oliena (dal 22 al 24 novembre), a Oristano (dal 29 novembre al 2 dicembre) e per la prima volta a Iglesias (dal 30 novembre al 2 dicembre). Non solo, in collaborazione con Sardegna teatro, il 18 novembre sbarcher\u00e0 a Nuoro al Teatro Eliseo, mentre il 24 sar\u00e0 a Isili con una serie di incontri con il Club Unesco locale.<\/p>\n<p>All\u2019iniziativa \u00e8 abbinato un contest fotografico su Instagram: #Scienzafutura. Chiunque pu\u00f2 partecipare basta avere un account instagram e seguire le indicazioni riportate nel sito internet che l\u2019accompagna la manifestazione (link pi\u00f9 sotto). Qui tutte le informazioni e il programma in dettaglio. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 24 Ott 2017 &#8211; Vita e macchina, natura e tecnologia, distinte e congiunte allo stesso tempo. \u00c8 l\u2019emblema scelto dagli organizzatori dell\u2019edizione numero 10&#8230;<\/p>\n","protected":false},"author":2,"featured_media":132552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149999"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=149999"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/132552"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=149999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=149999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=149999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}