{"id":149983,"date":"2017-10-24T12:18:08","date_gmt":"2017-10-24T10:18:08","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=149983"},"modified":"2017-10-24T12:18:08","modified_gmt":"2017-10-24T10:18:08","slug":"universita-farmaci-intelligenti-screening-sanitari-sicurezza-agroalimentare-se-ne-parla-a-cagliari","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/10\/24\/universita-farmaci-intelligenti-screening-sanitari-sicurezza-agroalimentare-se-ne-parla-a-cagliari\/","title":{"rendered":"Universit\u00e0 &#8211; Farmaci intelligenti, screening sanitari, sicurezza agroalimentare: se ne parla a Cagliari"},"content":{"rendered":"<p>Cagliari, 24 Ott 2017 - Da domani a venerd\u00ec 27 ottobre prossimo, dalle 14, la sala convegni della <a href=\"http:\/\/www.fondazionedisardegna.it\/index.php\">Fondazione di Sardegna<\/a> - via San Salvatore da Horta n. 2, Cagliari - ospita la terza edizione della conferenza internazionale OrbItaly (Organic bioeletronics Italy). Ai lavori partecipa una platea selezionata di ricercatori provenienti da tutto il mondo. L\u2019Universit\u00e0 di Cagliari \u00e8 stata scelta quale sede dell\u2019evento con la regia di<\/p>\n<p>La conferenza avr\u00e0 per oggetto i pi\u00f9 recenti risultati nel campo della bioelettronica, settore emergente a cavallo tra la Bioingegneria, l\u2019Elettronica e la Scienza dei materiali. \u201cUno scenario multidisciplinare che, grazie all\u2019uso di nuovi materiali funzionali (polimeri, biomateriali cos\u00ec come sistemi nanostrutturati), consente - spiega la professoressa Bonfiglio, presidente di Crs4, gi\u00e0 pro rettore dell\u2019ateneo di Cagliari - di sviluppare dispositivi elettronici e sistemi capaci di interfacciarsi e \u201cdialogare\u201d con gli organismi viventi. Un settore in cui il Dipartimento di ingegneria elettrica ed elettronica dell\u2019Universit\u00e0 di Cagliari svolge da anni ricerca di eccellenza riconosciuta e accreditata a livello internazionale\u201d.<\/p>\n<p>Ricercatori provenienti, oltre che dall\u2019Italia, anche da Stati Uniti, Austria, Germania, Svezia, Spagna, Francia e Regno Unito, presentano i risultati pi\u00f9 rilevanti ottenuti nei propri laboratori inerenti la realizzazione di materiali innovativi che, traendo ispirazione dai materiali esistenti in natura, siano in grado di mimare sistemi biologici e controllarli. \u201cQuesti studi offrono sbocchi applicativi e tecnologici nell\u2019ambito non soltanto dell\u2019indagine funzionale dei sistemi viventi, della diagnosi clinica e dello screening di massa, ma anche - aggiunge il professor Cosseddu, docente di Elettronica - sui fronti della sicurezza agroalimentare, della realizzazione di farmaci intelligenti e di biosensori che sfruttano l\u2019elettronica integrata con sistemi biologici\u201d.<\/p>\n<p>Domani alle 19 si tiene la premiazione delle tre migliori idee di sviluppo e ricerca formulate da ricercatori Under 35 impegnati nel settore. Alla cerimonia - supportata dal Crea, Centro servizi innovazione e imprenditoria dell\u2019Universit\u00e0 di Cagliari - prende parte Maria Chiara Di Guardo, pro rettore per l\u2019Innovazione. L\u2019evento \u00e8 stato curato dagli specialisti del Diee, coordinati da Annalisa Bonfiglio e Piero Cosseddu, Stefano Lai, Giulia Casula, Andrea Spanu, Corrado Napoli, Fabrizio Viola e Andrea Achilli. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 24 Ott 2017 &#8211; Da domani a venerd\u00ec 27 ottobre prossimo, dalle 14, la sala convegni della Fondazione di Sardegna &#8211; via San Salvatore&#8230;<\/p>\n","protected":false},"author":2,"featured_media":149984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149983"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=149983"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/149984"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=149983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=149983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=149983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}