{"id":149855,"date":"2017-10-20T15:50:23","date_gmt":"2017-10-20T13:50:23","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=149855"},"modified":"2017-10-20T15:50:23","modified_gmt":"2017-10-20T13:50:23","slug":"avrebbe-abusato-dalle-nipotina-di-9-anni-arrestato-50enne-per-violenza-sessuale-su-minori-e-pornografia-minorile","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/10\/20\/avrebbe-abusato-dalle-nipotina-di-9-anni-arrestato-50enne-per-violenza-sessuale-su-minori-e-pornografia-minorile\/","title":{"rendered":"Avrebbe abusato dalle nipotina di 9 anni: arrestato 50enne per violenza sessuale su minori e pornografia minorile,"},"content":{"rendered":"<p>Cagliari, 20 Ott 2017 - Secondo quanto emerso dalle indagini, il 50enne arrestato ieri notte dai carabinieri del Comando provinciale di Cagliari avrebbe abusato della nipote di nove anni, approfittando del fatto di essere uno di casa e padrino della bambina. Per questo, con le accuse di violenza sessuale su minori e pornografia minorile, l\u2019uomo, del Medio Campidano, \u00e8 finito in carcere.<\/p>\n<p>L'indagine \u00e8 scattata dopo la denuncia della madre (sorella della fermato) della bambina. La vittima avrebbe raccontato alla mamma delle attenzioni dello zio. Da qui gli accertamenti e il fermo con il sequestro di telefoni cellulari dove, in alcune schede, ci sarebbero foto anche della bambina, elemento pesante a carico del 50enne.<\/p>\n<p>Domani \u00e8 previsto l'interrogatorio di garanzia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 20 Ott 2017 &#8211; Secondo quanto emerso dalle indagini, il 50enne arrestato ieri notte dai carabinieri del Comando provinciale di Cagliari avrebbe abusato della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":139707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149855"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=149855"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/149855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/139707"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=149855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=149855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=149855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}