{"id":144105,"date":"2017-06-19T19:03:26","date_gmt":"2017-06-19T17:03:26","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=144105"},"modified":"2017-06-19T19:03:26","modified_gmt":"2017-06-19T17:03:26","slug":"scritte-intimidatorie-contro-vicesindaco-di-domusnovas-indagano-i-carabinieri-del-paese","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/19\/scritte-intimidatorie-contro-vicesindaco-di-domusnovas-indagano-i-carabinieri-del-paese\/","title":{"rendered":"Scritte intimidatorie contro vicesindaco di Domusnovas, indagano i carabinieri del paese."},"content":{"rendered":"<p>Domusnovas (Ca), 19 Giu 2017 - Questa mattina alle ore 08:30, a Domusnovas (Ca), i carabinieri della Stazione del paese nel corso di un servizio preventivo controllo del territorio hanno rinvenuto sul manto stradale di via Zurigo e di una strada di penetrazione agraria in direzione dello stabilimento \u201cRwm\u201d in localit\u00e0 \u201cmatte e conti\u201d,\u00a0prodotte con vernice spray di colore bianco dal tenore minatorio, indirizzate al vice sindaco pro-tempore del comune di Domusnovas,\u00a0Angelo Deidda, di 56 anni, del posto.<\/p>\n<p>Indagini in corso da parte dei militari della locale Stazione cc, al fine di verificare natura gesto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domusnovas (Ca), 19 Giu 2017 &#8211; Questa mattina alle ore 08:30, a Domusnovas (Ca), i carabinieri della Stazione del paese nel corso di un servizio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":144106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/144105"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=144105"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/144105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/144106"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=144105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=144105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=144105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}