{"id":143972,"date":"2017-06-16T13:23:35","date_gmt":"2017-06-16T11:23:35","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143972"},"modified":"2017-06-16T13:23:35","modified_gmt":"2017-06-16T11:23:35","slug":"personale-della-polizia-di-stato-di-sassari-arresta-un-44enne-per-danneggiamento-resistenza-violenza-lesioni-e-minacce-a-p-u","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/16\/personale-della-polizia-di-stato-di-sassari-arresta-un-44enne-per-danneggiamento-resistenza-violenza-lesioni-e-minacce-a-p-u\/","title":{"rendered":"Personale della Polizia di Stato di Sassari arresta un 44enne per danneggiamento, resistenza, violenza, lesioni e minacce a P.U."},"content":{"rendered":"<p>Sassari, 16 Giu 2017 - Nella serata di ieri, personale della Sezione Volanti della Questura di Sassari ha arrestato un 44enne sassarese, con precedenti di polizia, per danneggiamento, resistenza, violenza, lesioni e minacce a Pubblico Ufficiale.<\/p>\n<p>Gli agenti sono intervenuti presso un esercizio commerciale del centro, dove al loro arrivo hanno trovato una persona, palesemente ubriaca, intenta a discutere animatamente con una guardia giurata. L\u2019oggetto della controversia \u00e8 stato il comportamento tenuto, poco prima all\u2019interno dell\u2019attivit\u00e0, dall\u2019arrestato, che senza un apparente motivo aveva preso a calci uno scaffale con della merce esposta, ed invitato ad uscire, \u00e8 andato in escandescenza, assumendo un comportamento aggressivo.<\/p>\n<p>Dopo un primo controllo da parte dei poliziotti, l\u2019uomo, \u00e8 stato trovato in possesso di un coltello multiuso e nella circostanza, pur di sottrarsi al controllo, ha iniziato a spintonare i poliziotti. Poi, l\u2019atteggiamento violento dell\u2019uomo \u00e8 proseguito oltre che sull\u2019auto di servizio anche in Questura all\u2019interno delle celle di sicurezza, dove si \u00e8 accanito contro la porta blindata sferrando calci e pugni.<\/p>\n<p>Quindi il pregiudicato dopo le formalit\u00e0 di rito \u00e8 stato trattenuto e messo a disposizione dell\u2019A.G. competente, in attesa dell\u2019udienza di convalida prevista per oggi presso il Tribunale di Sassari.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari, 16 Giu 2017 &#8211; Nella serata di ieri, personale della Sezione Volanti della Questura di Sassari ha arrestato un 44enne sassarese, con precedenti di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":131179,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143972"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143972"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/131179"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}