{"id":143968,"date":"2017-06-16T10:59:57","date_gmt":"2017-06-16T08:59:57","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143968"},"modified":"2017-06-16T10:59:57","modified_gmt":"2017-06-16T08:59:57","slug":"truffa-aggravata-ai-danni-del-bilancio-comunitario-concluse-le-indagini-sullimprenditore-di-arzachena","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/16\/truffa-aggravata-ai-danni-del-bilancio-comunitario-concluse-le-indagini-sullimprenditore-di-arzachena\/","title":{"rendered":"\u201cTruffa aggravata ai danni del bilancio Comunitario: concluse le indagini sull\u2019imprenditore di Arzachena\u201d\u00a0\u00a0"},"content":{"rendered":"<p>Palau (SS), 16 Giu 2017 - I militari della Tenenza della Guardia di Finanza di Palau ha concluso nei giorni scorsi l\u2019operazione di servizio che nel febbraio scorso aveva portato all\u2019arresto di un imprenditore di Arzachena che, mediante il fraudolento utilizzo di vari soggetti giuridici allo stesso riconducibili e la loro fittizia interposizione era riuscito a percepire circa 200.000 euro di contributi pubblici a sostegno dell\u2019agricoltura.<\/p>\n<p>Gli ulteriori approfondimenti d\u2019indagine, portati avanti a seguito delle perquisizioni eseguite lo scorso febbraio, hanno consentito di confermare il grave quadro probatorio, tanto da consentire il sequestro di alcuni immobili intestati ad uno dei soggetti giuridici coinvolti quale applicazione di una misura cautelare reale avente ad oggetto il profitto del reato.<\/p>\n<p>I medesimi approfondimenti, l\u2019analisi delle contabilit\u00e0 e gli inevitabili controlli tributari, inoltre, hanno consentito di accertare come le fatture per operazioni inesistenti, utilizzate nell\u2019ambito della truffa al bilancio comunitario, siano state anche utilizzate nelle dichiarazioni fiscali relative alle quattro attivit\u00e0 d\u2019impresa riconducibili all\u2019indagato, nelle quali venivano riportati costi indeducibili per circa 300.000 euro (in alcuni casi questi si accompagnavano all\u2019indicazione di redditi fittizi finalizzati a dare coerenza al disegno criminoso) ed indebite detrazioni IVA per circa 59.814 euro, ponendo cos\u00ec in essere l\u2019ulteriore fattispecie penale di frode fiscale.<\/p>\n<p>Parallelamente al procedimento penale, inoltre, sono stati avviati, nei confronti dei responsabili, i procedimenti sanzionatori amministrativi per le frodi nell\u2019ambito degli aiuti in agricoltura, i quali, da un lato, prevedono l\u2019irrogazione di una sanzione amministrativa quantificata in rapporto agli illegittimi finanziamenti percepiti e, dall\u2019altro, consentono di far decadere i procedimenti di aiuti e di attivare le fideiussioni per il recupero delle somme indebitamente percepite, per le quali \u00e8 stata inoltrata una segnalazione di danno erariale alla competente Procura Regionale della Corte dei Conti.<\/p>\n<p>Il contrasto agli illeciti in materia di spesa pubblica costituisce una fondamentale linea d\u2019azione nell\u2019ambito delle funzioni di polizia economico-finanziaria del Corpo e comprende tutti gli interventi, le indagini di polizia giudiziaria e gli altri accertamenti rivolti alla prevenzione ed alla repressione di casi di indebita percezione e di malversazione relativi alle uscite dei bilanci nazionale, locale e comunitario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palau (SS), 16 Giu 2017 &#8211; I militari della Tenenza della Guardia di Finanza di Palau ha concluso nei giorni scorsi l\u2019operazione di servizio che&#8230;<\/p>\n","protected":false},"author":2,"featured_media":136395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143968"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143968"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/136395"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}