{"id":143900,"date":"2017-06-15T11:49:28","date_gmt":"2017-06-15T09:49:28","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143900"},"modified":"2017-06-15T11:49:28","modified_gmt":"2017-06-15T09:49:28","slug":"arrestato-marito-e-padre-degenere-dai-carabinieri-per-maltrattamenti-in-famiglia-continuati","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/15\/arrestato-marito-e-padre-degenere-dai-carabinieri-per-maltrattamenti-in-famiglia-continuati\/","title":{"rendered":"Arrestato marito e padre degenere dai carabinieri per maltrattamenti in famiglia continuati."},"content":{"rendered":"<p>Cagliari, 15 Giu 2017 - Nel corso della notte i carabinieri della Stazione Donori, dopo al richiesta di aiuto, sono intervenuti in abitazione privata di Sant\u2019Andrea Frius, via Marconi, per lite in famiglia. I militari una volta giunti sul posto hanno sentito le vittime dell\u2019aggressione, moglie e figlia, hanno dichiarato in arresto per maltrattamenti in famiglia, Achille Puddu, di 55 anni, del luogo.<\/p>\n<p>L'arrestato, che da circa un anno avrebbe comportamenti violenti, nella circostanza avrebbe percosso i familiari per futili motivi provocandogli delle ecchimosi per cui sono ricorse alle cure della Guardia medica del paese.<\/p>\n<p>Quindi l\u2019uomo \u00e8 stato portato in caserma in stato di arresto e trattenuto nell\u2019attesa della direttissima previsto per oggi davanti al giudice monocratico del Tribunale di Cagliari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 15 Giu 2017 &#8211; Nel corso della notte i carabinieri della Stazione Donori, dopo al richiesta di aiuto, sono intervenuti in abitazione privata di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":143901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143900"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143900"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/143901"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}