{"id":143892,"date":"2017-06-15T09:41:58","date_gmt":"2017-06-15T07:41:58","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143892"},"modified":"2017-06-15T09:41:58","modified_gmt":"2017-06-15T07:41:58","slug":"giovane-di-origini-africane-ma-nato-e-residente-a-cagliari-deferito-per-furto","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/15\/giovane-di-origini-africane-ma-nato-e-residente-a-cagliari-deferito-per-furto\/","title":{"rendered":"Giovane di origini africane ma nato e residente a Cagliari deferito per furto."},"content":{"rendered":"<p>Pula (Ca), 15 Giu 2017 - Ieri, i carabinieri della Stazione di Pula hanno deferito in stato di libert\u00e0 all\u2019A.G. del capoluogo sardo, Adhibi Khemais, di 19 anni, di origine africana ma nato e residente a Cagliari da molti anni.<\/p>\n<p>Secondo quanto accertato dai militari, si \u00e8 reso responsabile dei numerosi furti, alcuni dei quali sfociati in rapine, avvenuti nei giorni scorsi ai danni di cittadini e turisti che si trovavano nell\u2019area costiera e dei territori confinanti.<\/p>\n<p>Il ragazzo, senza un lavoro, pregiudicato e conosciuto alle forze dell\u2019ordine della localit\u00e0 balneare, risiede in localit\u00e0 \u201cSu Tintioni\u201d e, ieri mattina, ignaro del fatto che gli investigatori dell\u2019Arma fossero sulle sue tracce, si aggirava tranquillamente per le vie del centro turistico a bordo di una bicicletta, anch\u2019essa provento di furto.<\/p>\n<p>I carabinieri dopo aver riconosciuto il ragazzo, lo hanno bloccato e sottoposto a perquisizione personale e domiciliare e poi, nell\u2019abitazione del giovane pregiudicato, sono stati trovati numerosi oggetti di valore ottenuti dal pregiudicato attraverso svariati furti, tra cui telefoni cellulari, tablet e parti di impianti stereo. Inoltre, Adhibi Khemais, \u00e8 stato trovato in possesso di marijuana che, come lo stesso ha dichiarato, usa abitualmente.<\/p>\n<p>Quindi, ponendo un forte freno all\u2019attivit\u00e0 delittuosa, di cui il giovane risulta essere uno dei principali responsabili, i militari della Stazione cc di Pula hanno sequestrato gli oggetti ritrovati restituendoli ai legittimi proprietari, nonch\u00e9 la droga che lo stesso deteneva in casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pula (Ca), 15 Giu 2017 &#8211; Ieri, i carabinieri della Stazione di Pula hanno deferito in stato di libert\u00e0 all\u2019A.G. del capoluogo sardo, Adhibi Khemais,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":143893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143892"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143892"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/143893"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}