{"id":143840,"date":"2017-06-14T13:04:11","date_gmt":"2017-06-14T11:04:11","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143840"},"modified":"2017-06-14T13:04:11","modified_gmt":"2017-06-14T11:04:11","slug":"incensurato-di-cagliari-arrestato-dai-carabinieri-a-pirri-per-detenzione-ai-fini-di-spaccio-di-stupefacenti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/14\/incensurato-di-cagliari-arrestato-dai-carabinieri-a-pirri-per-detenzione-ai-fini-di-spaccio-di-stupefacenti\/","title":{"rendered":"Incensurato di Cagliari arrestato dai carabinieri a Pirri per detenzione ai fini di spaccio di stupefacenti."},"content":{"rendered":"<p>Cagliari, 14 Giu 2017 - Nella serata di ieri, i carabinieri del Nucleo investigativo del comando provinciale Cagliari e quelli della Stazione di Ca-Pirri, hanno arrestato nella flagranza del reato di detenzione ai fini di spaccio di sostanze stupefacenti, Mario Dess\u00ec, di 37 anni, disoccupato\u00a0incensurato, del capoluogo regionale.<\/p>\n<p>I militari,\u00a0nel corso di servizi di contrasto al fenomeno di uso e spaccio di stupefacenti,\u00a0a seguito della perquisizione del domicilio dell\u2019arrestato, hanno rinvenuto e sequestrato, occultati nella sua stanza da letto, 5 kg di hashish, suddivisi in 70 parti; 750 gr di marijuana, divisi in 5 buste in plastica sottovuoto; 70 gr di cocaina, suddivisi in confezioni in plastica; 200 gr\u00a0di sostanza da taglio; materiale vario per il confezionamento delle dosi; una bilancia elettronica funzionante e due cellulari utilizzati per l\u2019attivit\u00e0 di spaccio.<\/p>\n<p>Valore commerciale complessivo stimato in 25\/30.000 \u20ac<\/p>\n<p>L\u2019uomo, \u00e8 stato quindi dichiarato in arresto e ultimate le formalit\u00e0 di legge in caserma, \u00e8 stato accompagnato e rinchiuso presso il carcere di Ca-Uta in attesa delle successive fasi processuali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 14 Giu 2017 &#8211; Nella serata di ieri, i carabinieri del Nucleo investigativo del comando provinciale Cagliari e quelli della Stazione di Ca-Pirri, hanno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":143841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143840"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143840"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/143841"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}