{"id":143230,"date":"2017-06-03T11:00:26","date_gmt":"2017-06-03T09:00:26","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=143230"},"modified":"2017-06-03T11:00:26","modified_gmt":"2017-06-03T09:00:26","slug":"migranti-ancora-altri-clandestini-in-sardegna-soccorsi-e-portati-a-terra-18-migranti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/06\/03\/migranti-ancora-altri-clandestini-in-sardegna-soccorsi-e-portati-a-terra-18-migranti\/","title":{"rendered":"Migranti \u2013 Ancora altri clandestini in Sardegna, soccorsi e portati a terra 18 migranti"},"content":{"rendered":"<p>Cagliari, 3 Giu 2017 - Alle ore 12.00 di ieri, la sala operativa di del comando della capitaneria di porto ha ricevuto notizia, in merito all\u2019avvistamento di 7 presunti migranti a bordo di un\u2019imbarcazione in navigazione verso le coste sarde. Quindi \u00e8 stata comunicata la posizione alla motovedetta impegnata in attivit\u00e0 Frontex, la quale alle ore 14.15 ha intercettato l\u2019imbarcazione e causa peggioramento delle condizioni meteo ha proceduto al trasbordo degli occupanti prendendo a rimorchio il barchino e poi si \u00e8 diretta verso il porto di Sant\u2019Antioco dove ha poi ormeggiato alle ore 17.00 e subito dopo sono stati sbarcati i migranti e affidati ai carabinieri della Stazione del paese costiero per le formalit\u00e0 di competenza.<\/p>\n<p>Alle ore 00.55 di questa mattina \u00e8 stato poi disposto sempre dal comando della capitaneria di porto, l\u2019intervento della motovedetta favore di un barchino di circa 6 mt con 11 migranti a bordo in difficolt\u00e0 a circa 43 miglia a sud di Cagliari.<\/p>\n<p>Alle ore 04.40 l\u2019imbarcazione militare ha intercettato l\u2019imbarcazione in difficolt\u00e0 ed ha proceduto al trasbordo degli occupanti per poi dirigere verso il porto di Cagliari dove \u00e8 giunta alle ore 07.00.<\/p>\n<p>Qui i clandestini sono stati sbarcati e poi consegnati nelle mani degli agenti della Polizia di Stato di Cagliari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 3 Giu 2017 &#8211; Alle ore 12.00 di ieri, la sala operativa di del comando della capitaneria di porto ha ricevuto notizia, in merito&#8230;<\/p>\n","protected":false},"author":2,"featured_media":142253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143230"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=143230"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/143230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/142253"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=143230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=143230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=143230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}