{"id":142889,"date":"2017-05-26T15:14:37","date_gmt":"2017-05-26T13:14:37","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=142889"},"modified":"2017-05-26T15:14:37","modified_gmt":"2017-05-26T13:14:37","slug":"giovane-ozierese-arrestato-dal-personale-del-commissariato-di-p-s-di-olbia-per-detenzione-illecita-di-sostanze-stupefacenti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/05\/26\/giovane-ozierese-arrestato-dal-personale-del-commissariato-di-p-s-di-olbia-per-detenzione-illecita-di-sostanze-stupefacenti\/","title":{"rendered":"Giovane ozierese arrestato dal personale del Commissariato di P.S. di Olbia per detenzione illecita di sostanze stupefacenti."},"content":{"rendered":"<p>Olbia, 26 Mag 2017 - Nel corso del pomeriggio di ieri, personale del Commissariato P.S. di Olbia ha arrestato per detenzione illecita di sostanze stupefacenti, un 23enne, ozierese, con precedenti di polizia.<\/p>\n<p>Gli agenti, durante un\u2019operazione finalizzata al contrasto del traffico illecito di droga, hanno proceduto alla perquisizione di un\u2019abitazione situata nel territorio cittadino. All\u2019interno della casa, i poliziotti hanno rinvenuto 600 grammi circa di canapa indiana, contenuta in diversi barattoli di vetro o in sacchetti di plastica, nascosti all\u2019interno di alcuni mobili del soggiorno. In camera da letto, il giovane aveva inoltre, allestito una piccola serra, con un sistema di areazione e insonorizzazione, nella quale erano state messe ad essiccare sei piantine di marijuana di diverse altezze. All\u2019esterno dell\u2019abitazione rurale il 23enne aveva piantato altre piante di marijuana di varie dimensioni ed in vari stadi vegetativi.<\/p>\n<p>Quindi tutta la sostanza stupefacente \u00e8 stata sottoposta a sequestro ed il giovane \u00e8 stato dichiarato in arresto ed accompagnato presso gli uffici del Commissariato di P.S. dove dopo le formalit\u00e0 di rito, \u00e8 stato trattenuto nelle camere di sicurezza in attesa del procedimento di convalida previsto per oggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olbia, 26 Mag 2017 &#8211; Nel corso del pomeriggio di ieri, personale del Commissariato P.S. di Olbia ha arrestato per detenzione illecita di sostanze stupefacenti,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":135086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142889"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=142889"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/135086"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=142889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=142889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=142889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}