{"id":142863,"date":"2017-05-26T07:57:22","date_gmt":"2017-05-26T05:57:22","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=142863"},"modified":"2017-05-26T07:57:22","modified_gmt":"2017-05-26T05:57:22","slug":"gdf-cagliari-progetto-domus-aurea-eseguiti-controlli-e-verifiche-nel-settore-delle-locazioni-immobiliari-turistiche-sullintera-fascia-costiera-cagliaritana-e-scoperta-evasione-fiscale-di-qu","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/05\/26\/gdf-cagliari-progetto-domus-aurea-eseguiti-controlli-e-verifiche-nel-settore-delle-locazioni-immobiliari-turistiche-sullintera-fascia-costiera-cagliaritana-e-scoperta-evasione-fiscale-di-qu\/","title":{"rendered":"Gdf Cagliari, progetto Domus Aurea: eseguiti controlli e verifiche nel settore delle locazioni immobiliari turistiche sull\u2019intera fascia costiera cagliaritana e scoperta evasione fiscale di quasi 2 milioni di euro."},"content":{"rendered":"<p>Cagliari, 26 Mag 2017 - A conclusione di un anno di indagini, le Fiamme Gialle di Cagliari hanno portato a termine un\u2019articolata operazione a contrasto degli affitti in nero nelle zone a pi\u00f9 elevata vocazione turistica della provincia.<\/p>\n<p>Le indagini hanno tratto origine dagli esiti di un\u2019accurata analisi di contesto sviluppata tramite il controllo economico del territorio ed il monitoraggio delle unit\u00e0 immobiliari destinate a locazione nelle aree a maggior vocazione turistica.<\/p>\n<p>Sono stati, cos\u00ec, effettuati ben 83 tra verifiche e controlli che hanno permesso di constatare un\u2019evasione fiscale pari a pi\u00f9 di 1.800.000 euro ed il mancato versamento dell\u2019imposta di registro per poco meno di 16.000 euro.<\/p>\n<p>L\u2019attivit\u00e0 operativa ha interessato una realt\u00e0 territoriale, quale quella della provincia cagliaritana, caratterizzata dalla presenza di un esteso e naturalisticamente invidiabile tratto costiero che, per il richiamo dei suoi paesaggi, ha favorito i presupposti per un importante sviluppo immobiliare. In tale ambito, accanto ad hotel, villaggi turistici e resort, hanno trovato allocazione anche unit\u00e0 abitative private, di diverse tipologie, destinate prevalentemente alle locazioni temporanee per fini turistici.<\/p>\n<p>Infatti, durante le attivit\u00e0 ispettive, i finanzieri si sono imbattuti sia in villette a schiera che in immobili di prestigio e, fra questi, ville di lusso accessoriate con ogni confort. Quindi i militari hanno passato al setaccio i comuni e le localit\u00e0 turistiche pi\u00f9 rinomate: da Portoscuso a Villaputzu, da Castiadas a Carloforte, passando per Teulada, Chia, Pula, Villasimius, Cagliari e Quartu S.Elena.<\/p>\n<p>La selezione dei target nei cui confronti orientare l\u2019attivit\u00e0 di controllo ha tratto, quindi, origine dall\u2019esame degli elementi materialmente acquisiti sul territorio nonch\u00e9 dalla consultazione delle principali piattaforme on line di settore, attivit\u00e0 ricognitive integrate poi dalla valutazione della documentazione di interesse acquisita presso locali agenzie di intermediazione.<\/p>\n<p>I dati sono poi confluiti in un quadro generale pi\u00f9 strutturato per il chiarimento delle posizioni fiscalmente pi\u00f9 \u201csensibili\u201d: a tal fine, hanno costituito ulteriore parametro di riferimento le recensioni pubblicate online (sui siti specializzati piuttosto che su forum di discussione o blog) concernenti la descrizione e la valutazione dei servizi offerti, l\u2019indicazione dei periodi di maggior affluenza turistica e la disponibilit\u00e0 di camere e\/o posti letto.<\/p>\n<p>Il successivo riscontro degli immobili a livello catastale e la conseguente loro riconducibilit\u00e0 agli effettivi proprietari, ha consentito pertanto di disporre di tutti gli elementi necessari all\u2019avvio dei controlli finalizzati alla verifica degli adempimenti fiscali sotto il profilo delle imposte dirette e di registro.<\/p>\n<p>Durante le attivit\u00e0 ispettive molteplici e diversificate sono state le situazioni che si sono presentate agli occhi degli investigatori.<\/p>\n<p>In pi\u00f9 di un caso, \u00e8 stata riscontrata la riconducibilit\u00e0 di pi\u00f9 immobili, tutti destinati a locazioni completamente o in buona parte non dichiarate, ad un unico soggetto, la cui posizione fiscale conosciuta all\u2019erario evidenziava, invece, una situazione reddituale ben pi\u00f9 modesta.<\/p>\n<p>In un altro caso \u00e8 stata individuata una vera e propria impresa esercente l\u2019attivit\u00e0 di intermediazione immobiliare senza le prescritte autorizzazioni, con annessa fornitura di prestazioni accessorie (quali transfer, pulizie, cambio biancheria, ecc.) In completa evasione d\u2019imposta.<\/p>\n<p>In queste circostanze, come in altre nelle qualit\u00e0 stata riscontrata una evidente sproporzione tra quanto dichiarato e quanto in realt\u00e0 percepito, al fine di ricostruire compiutamente la posizione reddituale dei soggetti sottoposti a controllo, le Fiamme Gialle hanno proceduto all\u2019esecuzione di indagini finanziarie, esaminando tutte le transazioni compiute e le movimentazioni di denaro connesse.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 26 Mag 2017 &#8211; A conclusione di un anno di indagini, le Fiamme Gialle di Cagliari hanno portato a termine un\u2019articolata operazione a contrasto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":139629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142863"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=142863"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/139629"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=142863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=142863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=142863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}