{"id":142801,"date":"2017-05-25T11:55:21","date_gmt":"2017-05-25T09:55:21","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=142801"},"modified":"2017-05-25T11:55:21","modified_gmt":"2017-05-25T09:55:21","slug":"polizia-di-stato-di-oristano-si-attiva-per-assistere-e-trasferire-a-roma-una-giovane-donna-in-stato-di-gravidanza","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/05\/25\/polizia-di-stato-di-oristano-si-attiva-per-assistere-e-trasferire-a-roma-una-giovane-donna-in-stato-di-gravidanza\/","title":{"rendered":"Polizia di Stato di Oristano si attiva per assistere e trasferire a Roma una giovane donna in stato di gravidanza."},"content":{"rendered":"<p>Oristano, 25 Mag 2017 - Il Settimo Reparto Volo della Polizia di Stato ha effettuato un trasporto Sanitario Urgente di una giovane donna in stato di gravidanza, dall\u2019Ospedale \u201cSan Martino\u201d di Oristano al Policlinico \u201cGemelli\u201d di Roma.<\/p>\n<p>Poco dopo le 13:00 del 23 maggio scorso, la Prefettura di Oristano ha messo in allarme il Dirigente del 7\u00b0 Reparto Volo della Polizia di Stato, Dr. Mauro Bernacchia, di stanza presso l\u2019Aeroporto \u201cErnesto Campanelli\u201d di Oristano \u2013 Fenosu, di una emergenza sanitaria che comporta l\u2019immediato trasporto aereo di una giovane donna in stato interessante, dall\u2019Ospedale \u201cSan Martino\u201d di Oristano al Policlinico \u201cGemelli\u201d di Roma.<\/p>\n<p>Attivata immediatamente la procedura di emergenza, Piloti e Specialisti hanno poi predisposto il piano di volo e preparano alla partenza l\u2019Agusta AW139, nuovissimo elicottero di cui \u00e8 stato recentemente dotato il Reparto.<\/p>\n<p>Alle ore 15:35, la paziente \u00e8 giunto in aeroporto a bordo di un\u2019ambulanza del 118 e viene caricata a bordo del velivolo della Polizia di Stato.<\/p>\n<p>Ore 15:50, l\u2019elicottero \u00e8 decollato alla volta del Policlinico \u201cGemelli\u201d ove, dopo un\u2019ora e 40 minuti di volo, \u00e8 atterrato regolarmente e la paziente viene immediatamente affidata nelle mani dei sanitari.<\/p>\n<p>All\u2019equipaggio dell\u2019Agusta della Polizia di Stato non resta che rientrare in sede con la consapevolezza d\u2019avere portato a termine una missione che pu\u00f2 avere contribuito a salvare due vite<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oristano, 25 Mag 2017 &#8211; Il Settimo Reparto Volo della Polizia di Stato ha effettuato un trasporto Sanitario Urgente di una giovane donna in stato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":142802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142801"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=142801"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/142802"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=142801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=142801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=142801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}