{"id":142703,"date":"2017-05-23T19:50:18","date_gmt":"2017-05-23T17:50:18","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=142703"},"modified":"2017-05-23T19:50:18","modified_gmt":"2017-05-23T17:50:18","slug":"due-extracomunitari-aggrediscono-e-rapinano-una-ragazza-di-16-anni-mentre-scendeva-dallautobus-di-linea","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/05\/23\/due-extracomunitari-aggrediscono-e-rapinano-una-ragazza-di-16-anni-mentre-scendeva-dallautobus-di-linea\/","title":{"rendered":"Due extracomunitari aggrediscono e rapinano una ragazza di 16 anni mentre scendeva dall\u2019autobus di linea."},"content":{"rendered":"<p>Cagliari, 23 Mag 2017 - Questa mattina, a Decimomannu (Ca), degli sconosciuti, verosimilmente cittadini extracomunitari, hanno rapinato una minorenne di 16 anni, di Assemini, studentessa.<\/p>\n<p>La vittima, che viaggiava a bordo dell\u2019autobus linea 9 del C.T.M. di Cagliari, \u00e8 scesa alla fermata di via Nazionale, insieme ai malfattori, anche loro a bordo del mezzo.<\/p>\n<p>Quindi, i due, dopo averla seguita sino alla vicina via Romagna, l\u2019hanno bloccato e poi gli hanno sottratto lo zaino contenente il telefono cellulare ed il portafoglio, per poi darsi alla fuga a piedi.<\/p>\n<p>La ragazza, visitata dalla locale guardia medica, ha riportato lievi escoriazioni e lividi, giudicati guaribili in cinque giorni.<\/p>\n<p>Sono ora in corso le indagini da parte dei carabinieri della Stazione di Decimomannu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 23 Mag 2017 &#8211; Questa mattina, a Decimomannu (Ca), degli sconosciuti, verosimilmente cittadini extracomunitari, hanno rapinato una minorenne di 16 anni, di Assemini, studentessa.&#8230;<\/p>\n","protected":false},"author":2,"featured_media":138618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142703"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=142703"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/138618"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=142703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=142703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=142703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}