{"id":142608,"date":"2017-05-22T14:31:25","date_gmt":"2017-05-22T12:31:25","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=142608"},"modified":"2017-05-22T14:31:25","modified_gmt":"2017-05-22T12:31:25","slug":"motociclista-olbiese-non-si-ferma-allalt-dei-carabinieri-fermato-dopo-un-inseguimento-di-10-km-e-poi-denunciato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/05\/22\/motociclista-olbiese-non-si-ferma-allalt-dei-carabinieri-fermato-dopo-un-inseguimento-di-10-km-e-poi-denunciato\/","title":{"rendered":"Motociclista olbiese non si ferma all\u2019alt dei carabinieri: fermato dopo un inseguimento di 10 km e poi denunciato."},"content":{"rendered":"<p>Olbia, 22 Mag 2017 - Durante un normale servizio di controllo per la prevenzione dei reati in genere nella nota localit\u00e0 balneare di \u201cPorto Istana\u201d, dove in passato sono stati perpetrati alcuni furti agli autoveicoli parcheggiati, i Carabinieri della Stazione di Olbia Poltu Quadu hanno notato un giovane, con un casco in mano, che si stava dirigendo verso la zona adibita a parcheggio, ma che alla vista dei militari, con fare nervoso, \u00e8 tornato indietro facendo finta di aspettare qualcuno.<\/p>\n<p>Quindi i militari, che al momento erano a piedi e non sono riusciti a raggiungere l\u2019uomo, insospettiti, si sono allontanati fermandosi a circa un km di distanza, sull\u2019unica strada percorribile in uscita, dove hanno eseguito un posto di controllo alla circolazione stradale con l\u2019intento di controllare il motociclista notato poco prima. E, infatti, il loro intuito \u00e8 stato premiato perch\u00e9 dopo circa mezz\u2019ora hanno intimato l\u2019alt al sopraggiungere di una Honda Hornet il cui conducente ha inizialmente rallentato per poi accelerare e darsi alla fuga.<\/p>\n<p>A questo punto gli uomini dell\u2019Arma hanno inseguito il centauro e nel contempo hanno diramato l\u2019allarme alla Centrale Operativa. Poi, un equipaggio della Sezione Radiomobile del Reparto Territoriale, dopo un inseguimento di 10 km terminato nei pressi del campo sportivo di Olbia, \u00e8 riuscito a bloccare definitivamente il fuggitivo che non ha potuto fare altro che fermarsi.<\/p>\n<p>In seguito, durante il controllo, \u00e8 risultato che il conducente A.S., do 41 anni, di olbiese, fosse sprovvisto di patente di guida perch\u00e9 mai conseguita, senza copertura assicurativa e con revisione scaduta. Tutto ci\u00f2 ha comportato il sequestro della moto e la contestazione delle violazioni alle norme del Codice della Strada, per un totale di oltre 6000 euro. Oltre a questo \u00e8 stato denunciato per non essersi fermato all\u2019alt e la successiva perquisizione ha permesso il rinvenimento di un coltello che gli coster\u00e0 un ulteriore capo di imputazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olbia, 22 Mag 2017 &#8211; Durante un normale servizio di controllo per la prevenzione dei reati in genere nella nota localit\u00e0 balneare di \u201cPorto Istana\u201d,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":142471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142608"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=142608"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/142608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/142471"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=142608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=142608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=142608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}