{"id":141466,"date":"2017-04-28T11:20:13","date_gmt":"2017-04-28T09:20:13","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=141466"},"modified":"2017-04-28T11:20:13","modified_gmt":"2017-04-28T09:20:13","slug":"atto-intimidatorio-contro-sindaco-di-siniscola-finta-bomba-davanti-al-suo-bar-caffetteria","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/04\/28\/atto-intimidatorio-contro-sindaco-di-siniscola-finta-bomba-davanti-al-suo-bar-caffetteria\/","title":{"rendered":"Atto intimidatorio contro sindaco di Siniscola: finta bomba davanti al suo bar caffetteria."},"content":{"rendered":"<p>Siniscola (Nu), 28 Apr 2017 \u2013 Nuovo atto intimidatorio contro gli amministratori nella provincia nuorese. Infatti, stamane, alle ore 5.00 circa, il sindaco di Siniscola Pier Luigi Farris ha rinvenuto davanti alla porta d'ingresso del suo bar \"Teo bar caffetteria\", ubicato in via Alcide De Gasperi, un pacco sospetto.<\/p>\n<p>Sul posto sono intervenuti i Carabinieri della Compagnia di Siniscola e l'artificiere antisabotaggio del Comando Provinciale di Nuoro che ha constatato trattarsi di un finto ordigno confezionato con due detonatori veri e sostanza solo in apparenza esplosiva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siniscola (Nu), 28 Apr 2017 \u2013 Nuovo atto intimidatorio contro gli amministratori nella provincia nuorese. Infatti, stamane, alle ore 5.00 circa, il sindaco di Siniscola&#8230;<\/p>\n","protected":false},"author":2,"featured_media":141463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/141466"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=141466"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/141466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/141463"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=141466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=141466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=141466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}